{"id":6510,"date":"2024-08-27T13:30:42","date_gmt":"2024-08-27T16:30:42","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=6510"},"modified":"2024-08-27T13:30:42","modified_gmt":"2024-08-27T16:30:42","slug":"corte-de-suministro-electrico-afecta-a-240-clientes-en-salamanca","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2024\/08\/27\/corte-de-suministro-electrico-afecta-a-240-clientes-en-salamanca\/","title":{"rendered":"Corte de suministro el\u00e9ctrico afecta a 240 clientes en Salamanca"},"content":{"rendered":"<p><strong>La informaci\u00f3n fue publicada por la empresa el\u00e9ctrica CGE.<\/strong><!--more--><\/p>\n<p>Desde la empresa el\u00e9ctrica <a href=\"https:\/\/www.cge.cl\/\" rel=\"nofollow\">CGE<\/a>, indican que un corte de suministro afecta a 240 clientes en la comuna de <strong>Salamanca<\/strong>.<\/p>\n<p>Nuestro sistema autom\u00e1tico informa que el sector afectado por el corte de suministro corresponde a <strong>Ruta D-827, Poblaci\u00f3n La Florida, Se\u00f1or de la Tierra, Salamanca, Provincia de Choapa, Regi\u00f3n de Coquimbo, 1950000, Chile<\/strong>.<\/p>\n<h2>Causa de la alteraci\u00f3n de suministro<\/h2>\n<p>Desde la empresa el\u00e9ctrica indican que la falla se encuentra en <strong>investigaci\u00f3n<\/strong>.<\/p>\n<h3>Hora estimada de restablecimiento del servicio<\/h3>\n<p>Clientes afectados: 240 Restauraci\u00f3n estimada: 27\/08\/2024 16:30 hrs<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La informaci\u00f3n fue publicada por la empresa el\u00e9ctrica CGE.<\/p>\n","protected":false},"author":2,"featured_media":6509,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[7,5],"tags":[],"class_list":["post-6510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cge","category-ultimo-minuto"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2024\/08\/cge-109.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/6510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=6510"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/6510\/revisions"}],"predecessor-version":[{"id":6511,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/6510\/revisions\/6511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/6509"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=6510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=6510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=6510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}