{"id":3884,"date":"2024-04-08T17:30:58","date_gmt":"2024-04-08T20:30:58","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=3884"},"modified":"2024-04-08T17:30:58","modified_gmt":"2024-04-08T20:30:58","slug":"corte-de-suministro-electrico-afecta-a-905-clientes-en-coquimbo","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2024\/04\/08\/corte-de-suministro-electrico-afecta-a-905-clientes-en-coquimbo\/","title":{"rendered":"Corte de suministro el\u00e9ctrico afecta a 905 clientes en Coquimbo"},"content":{"rendered":"<p><strong>La informaci\u00f3n fue publicada por la empresa el\u00e9ctrica CGE.<\/strong><!--more--><\/p>\n<p>Desde la empresa el\u00e9ctrica <a href=\"https:\/\/www.cge.cl\/\" rel=\"nofollow\">CGE<\/a>, indican que un corte de suministro afecta a 905 clientes en la comuna de <strong>Coquimbo<\/strong>.<\/p>\n<p>Nuestro sistema autom\u00e1tico informa que el sector afectado por el corte de suministro corresponde a <strong>Parque Nacional Chilo\u00e9, Bosque San Carlos, Tierras Blancas, Coquimbo, Provincia de Elqui, Regi\u00f3n de Coquimbo, 1720700, Chile<\/strong>.<\/p>\n<h2>Causa de la alteraci\u00f3n de suministro<\/h2>\n<p>Desde la empresa el\u00e9ctrica indican que la falla se encuentra en <strong>investigaci\u00f3n<\/strong>.<\/p>\n<h3>Hora estimada de restablecimiento del servicio<\/h3>\n<p>Clientes afectados: 905 Restauraci\u00f3n estimada: 08\/04\/2024 21:30 hrs<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La informaci\u00f3n fue publicada por la empresa el\u00e9ctrica CGE.<\/p>\n","protected":false},"author":2,"featured_media":3883,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[7,5],"tags":[],"class_list":["post-3884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cge","category-ultimo-minuto"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2024\/04\/cge-23.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/3884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=3884"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/3884\/revisions"}],"predecessor-version":[{"id":3885,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/3884\/revisions\/3885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/3883"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=3884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=3884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=3884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}