{"id":26579,"date":"2026-05-09T17:14:42","date_gmt":"2026-05-09T20:14:42","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=26579"},"modified":"2026-05-09T17:14:42","modified_gmt":"2026-05-09T20:14:42","slug":"fiscalia-investiga-el-caso-de-explotacion-sexual-infantil-vinculado-a-michael-hidalgo-en-iquique","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2026\/05\/09\/fiscalia-investiga-el-caso-de-explotacion-sexual-infantil-vinculado-a-michael-hidalgo-en-iquique\/","title":{"rendered":"Fiscal\u00eda investiga el caso de explotaci\u00f3n sexual infantil vinculado a &#8220;Michael Hidalgo&#8221; en Iquique"},"content":{"rendered":"<p>La <a href=\"https:\/\/www.fiscaliadechile.cl\/\">Fiscal\u00eda<\/a> mantiene activa su labor de investigaci\u00f3n para la identificaci\u00f3n de las ni\u00f1as cuyas im\u00e1genes fueron halladas en registros audiovisuales en el tel\u00e9fono celular de Sebasti\u00e1n E.P.U., un imputado por el delito de explotaci\u00f3n sexual infantil, quien opera bajo el nombre de \u00abMichael Hidalgo\u00bb y actualmente se encuentra en prisi\u00f3n preventiva.<\/p>\n<p>De acuerdo con Camila Albarrac\u00edn, fiscal adjunta de la <a href=\"https:\/\/www.fiscaliadechile.cl\/\">Fiscal\u00eda<\/a> Local de Iquique, el hallazgo de este material audiovisual no solo confirm\u00f3 el almacenamiento, sino tambi\u00e9n la fabricaci\u00f3n de evidencia de explotaci\u00f3n sexual infantil. Este caso subraya la gravedad del delito y la necesidad de una pronta investigaci\u00f3n criminal.<\/p>\n<p>El imputado residi\u00f3 en distintas regiones del pa\u00eds, incluyendo La Serena, Antofagasta, zonas de la Regi\u00f3n del Biob\u00edo, La Araucan\u00eda y \u00d1uble, entre 2019 y 2023. Ante este contexto de explotaci\u00f3n de menores, el Ministerio P\u00fablico ha lanzado un llamado urgente a posibles v\u00edctimas, familiares o cualquier persona con contacto con el sujeto, garantizando mecanismos de resguardo y protecci\u00f3n para quienes entreguen antecedentes sobre este caso de explotaci\u00f3n.<\/p>\n<p>La fiscal\u00eda reiter\u00f3 que el Ministerio P\u00fablico cuenta con la capacidad t\u00e9cnica para proteger tanto a las v\u00edctimas como a los testigos que aporten informaci\u00f3n vital, pudiendo realizar todo en reserva absoluta para garantizar la privacidad. Dado que los registros audiovisuales fueron captados entre 2019 y 2020, las posibles v\u00edctimas de esta explotaci\u00f3n sexual infantil tendr\u00edan actualmente entre 8 y 10 a\u00f1os.<\/p>\n<p>Las diligencias investigativas han incluido el uso de avanzada inteligencia artificial y herramientas tecnol\u00f3gicas por parte de <a href=\"https:\/\/www.carabineros.cl\/\">Carabineros<\/a>. A pesar de estos esfuerzos, a\u00fan no se ha podido establecer la identidad de las v\u00edctimas. Por ello, la fiscal\u00eda enfatiz\u00f3 el llamado a entregar cualquier informaci\u00f3n que permita avanzar en la identificaci\u00f3n de estas ni\u00f1as o posibles testigos, con el objetivo primordial de brindar cuidado, atenci\u00f3n y reparaci\u00f3n integral a las v\u00edctimas de este grave delito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda mantiene activa su labor de investigaci\u00f3n para la identificaci\u00f3n de las ni\u00f1as cuyas im\u00e1genes fueron halladas en registros audiovisuales en el tel\u00e9fono celular de Sebasti\u00e1n E.P.U., un imputado por el delito de explotaci\u00f3n sexual infantil, quien opera bajo el nombre de \u00abMichael Hidalgo\u00bb y actualmente se encuentra en prisi\u00f3n preventiva. De acuerdo con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26578,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[21],"tags":[],"class_list":["post-26579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2026\/05\/mediapiaiextstaticimg_webpAllanamientosFiscalia_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/26579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=26579"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/26579\/revisions"}],"predecessor-version":[{"id":26580,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/26579\/revisions\/26580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/26578"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=26579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=26579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=26579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}