{"id":25176,"date":"2026-03-23T20:41:54","date_gmt":"2026-03-23T23:41:54","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=25176"},"modified":"2026-03-23T20:41:54","modified_gmt":"2026-03-23T23:41:54","slug":"asaltante-de-bancoestado-con-cancer-quedo-en-prision-preventiva","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2026\/03\/23\/asaltante-de-bancoestado-con-cancer-quedo-en-prision-preventiva\/","title":{"rendered":"Asaltante de BancoEstado con c\u00e1ncer qued\u00f3 en prisi\u00f3n preventiva."},"content":{"rendered":"<p>El imputado que asalt\u00f3 un BancoEstado en Providencia qued\u00f3 en prisi\u00f3n preventiva. La defensa se\u00f1al\u00f3 que su actuar fue debido a una situaci\u00f3n extrema: se encuentra diagnosticado con c\u00e1ncer. El il\u00edcito ocurri\u00f3 en la ma\u00f1ana de este lunes, frente al Hospital Salvador, donde el individuo \u2014que ven\u00eda vestido de terno\u2014 apareci\u00f3 con un arma de aire comprimido. El hombre habr\u00eda amenazado al guardia del recinto, para posteriormente entrar con la intenci\u00f3n de cometer el robo antes del horario de apertura.<\/p>\n<p>El acusado intimid\u00f3 a los trabajadores y les sustrajo sus pertenencias. El sujeto intent\u00f3 huir escalando una reja perimetral y se dirigi\u00f3 a otra propiedad, pero fue capturado por <a href=\"https:\/\/www.carabineros.cl\/\">Carabineros<\/a>. En la audiencia de formalizaci\u00f3n, se revel\u00f3 que el imputado fue diagnosticado con c\u00e1ncer. La defensa del detenido indic\u00f3 que sus acciones pudieron haber sido por lo antes mencionado. Sin embargo, la magistrada rechaz\u00f3 la solicitud de la defensa y decret\u00f3 la medida de prisi\u00f3n preventiva. Se fij\u00f3 un plazo de investigaci\u00f3n de 80 d\u00edas.<\/p>\n<p><small><i><strong>Aviso de transparencia:<\/strong> Este art\u00edculo ha sido elaborado con la asistencia de Inteligencia Artificial para optimizar el procesamiento de informaci\u00f3n. Sin embargo, todo el contenido ha sido revisado, editado y validado por el equipo period\u00edstico de <strong><a href=\"https:\/\/laserenaradio.cl\/web\/\">LaSerenaRadio.cl<\/a><\/strong>, garantizando nuestra l\u00ednea editorial y veracidad informativa.<\/i><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El imputado que asalt\u00f3 un BancoEstado en Providencia qued\u00f3 en prisi\u00f3n preventiva. La defensa se\u00f1al\u00f3 que su actuar fue debido a una situaci\u00f3n extrema: se encuentra diagnosticado con c\u00e1ncer. El il\u00edcito ocurri\u00f3 en la ma\u00f1ana de este lunes, frente al Hospital Salvador, donde el individuo \u2014que ven\u00eda vestido de terno\u2014 apareci\u00f3 con un arma de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9076,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-25176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2024\/12\/laserenaradio_nacional.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/25176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=25176"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/25176\/revisions"}],"predecessor-version":[{"id":25177,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/25176\/revisions\/25177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/9076"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=25176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=25176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=25176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}