{"id":25140,"date":"2026-03-22T10:13:11","date_gmt":"2026-03-22T13:13:11","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=25140"},"modified":"2026-03-22T10:13:11","modified_gmt":"2026-03-22T13:13:11","slug":"emiten-un-aviso-por-precipitaciones-normales-a-moderadas-en-corto-periodo-de-tiempo-en-zonas-de-las-regiones-de-los-lagos-y-aysen","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2026\/03\/22\/emiten-un-aviso-por-precipitaciones-normales-a-moderadas-en-corto-periodo-de-tiempo-en-zonas-de-las-regiones-de-los-lagos-y-aysen\/","title":{"rendered":"Emiten un Aviso por Precipitaciones Normales a Moderadas en corto periodo de tiempo en zonas de las regiones de Los Lagos y Ays\u00e9n"},"content":{"rendered":"<p>Desde la Direcci\u00f3n Meteorol\u00f3gica de Chile, emitieron el Aviso A148\/2026 por Precipitaciones debido a la condici\u00f3n sin\u00f3ptica Sistema frontal.<\/p>\n<p>En detalle, la <a href=\"http:\/\/www.meteochile.gob.cl\/PortalDMC-web\/index.xhtml\" rel=\"nofollow\">Direcci\u00f3n Meteorol\u00f3gica de Chile<\/a>, indica que este fen\u00f3meno se encontrar\u00e1 vigente desde <strong>la ma\u00f1ana del lunes 23 de marzo del 2026<\/strong> y hasta <strong>la noche del lunes 23 de marzo del 2026<\/strong>.<\/p>\n<p>Las zonas afectadas por la condici\u00f3n ser\u00edan: Los Lagos (Litoral Interior, Cordillera Austral)<br \/>Ays\u00e9n (Litoral Interior Norte, Cordillera Austral Norte, Cordillera Austral Sur)<\/p>\n<p>Debido a esta condici\u00f3n, se llama a tener precauci\u00f3n y cautela por el Aviso vigente por Precipitaciones Normales a Moderadas en corto periodo de tiempo en zonas de las regiones de Los Lagos y Ays\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la Direcci\u00f3n Meteorol\u00f3gica de Chile, emitieron el Aviso A148\/2026 por Precipitaciones debido a la condici\u00f3n sin\u00f3ptica Sistema frontal. En detalle, la Direcci\u00f3n Meteorol\u00f3gica de Chile, indica que este fen\u00f3meno se encontrar\u00e1 vigente desde la ma\u00f1ana del lunes 23 de marzo del 2026 y hasta la noche del lunes 23 de marzo del 2026. Las [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9076,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-25140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2024\/12\/laserenaradio_nacional.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/25140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=25140"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/25140\/revisions"}],"predecessor-version":[{"id":25141,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/25140\/revisions\/25141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/9076"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=25140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=25140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=25140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}