{"id":24941,"date":"2026-03-17T14:23:56","date_gmt":"2026-03-17T17:23:56","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=24941"},"modified":"2026-03-17T14:23:56","modified_gmt":"2026-03-17T17:23:56","slug":"emiten-un-aviso-por-precipitaciones-normales-a-moderadas-en-corto-periodo-de-tiempo-en-zonas-de-las-regiones-de-la-araucania-y-los-rios","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2026\/03\/17\/emiten-un-aviso-por-precipitaciones-normales-a-moderadas-en-corto-periodo-de-tiempo-en-zonas-de-las-regiones-de-la-araucania-y-los-rios\/","title":{"rendered":"Emiten un Aviso por Precipitaciones Normales a Moderadas en corto periodo de tiempo en zonas de las regiones de La Araucan\u00eda y Los R\u00edos"},"content":{"rendered":"<p>Desde la Direcci\u00f3n Meteorol\u00f3gica de Chile, emitieron el Aviso A135\/2026 por Precipitaciones debido a la condici\u00f3n sin\u00f3ptica Sistema frontal.<\/p>\n<p>En detalle, la <a href=\"http:\/\/www.meteochile.gob.cl\/PortalDMC-web\/index.xhtml\" rel=\"nofollow\">Direcci\u00f3n Meteorol\u00f3gica de Chile<\/a>, indica que este fen\u00f3meno se encontrar\u00e1 vigente desde <strong>la tarde del mi\u00e9rcoles 18 de marzo del 2026<\/strong> y hasta <strong>la madrugada del jueves 19 de marzo del 2026<\/strong>.<\/p>\n<p>Las zonas afectadas por la condici\u00f3n ser\u00edan: La Araucan\u00eda (Litoral, Precordillera, Cordillera)<br \/>Los R\u00edos (Litoral, Cordillera Costa, Valle, Precordillera, Cordillera)<\/p>\n<p>Debido a esta condici\u00f3n, se llama a tener precauci\u00f3n y cautela por el Aviso vigente por Precipitaciones Normales a Moderadas en corto periodo de tiempo en zonas de las regiones de La Araucan\u00eda y Los R\u00edos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la Direcci\u00f3n Meteorol\u00f3gica de Chile, emitieron el Aviso A135\/2026 por Precipitaciones debido a la condici\u00f3n sin\u00f3ptica Sistema frontal. En detalle, la Direcci\u00f3n Meteorol\u00f3gica de Chile, indica que este fen\u00f3meno se encontrar\u00e1 vigente desde la tarde del mi\u00e9rcoles 18 de marzo del 2026 y hasta la madrugada del jueves 19 de marzo del 2026. Las [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9076,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-24941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2024\/12\/laserenaradio_nacional.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=24941"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24941\/revisions"}],"predecessor-version":[{"id":24942,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24941\/revisions\/24942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/9076"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=24941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=24941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=24941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}