{"id":24810,"date":"2026-03-13T22:01:19","date_gmt":"2026-03-14T01:01:19","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=24810"},"modified":"2026-03-13T22:01:19","modified_gmt":"2026-03-14T01:01:19","slug":"a-solicitud-de-la-fiscalia-tribunal-controlo-la-detencion-de-profugo-de-la-justicia-por-delitos-sexuales-que-fue-detenido-por-carabineros","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2026\/03\/13\/a-solicitud-de-la-fiscalia-tribunal-controlo-la-detencion-de-profugo-de-la-justicia-por-delitos-sexuales-que-fue-detenido-por-carabineros\/","title":{"rendered":"A solicitud de la Fiscal\u00eda: Tribunal control\u00f3 la detenci\u00f3n de pr\u00f3fugo de la justicia por delitos sexuales que fue detenido por Carabineros"},"content":{"rendered":"<p>Tras solicitud del Ministerio P\u00fablico, el Juzgado de Garant\u00eda de Chile Chico control\u00f3 la detenci\u00f3n de un imputado que permanec\u00eda pr\u00f3fugo de la justicia por delitos sexuales, el cual fue detenido por personal de Carabineros. Seg\u00fan explic\u00f3 la Fiscal Jefe de Cochrane y Chile Chico, Estefan\u00eda Leiva, el \u201c12 de marzo del a\u00f1o 2026, personal de Carabineros de la Tercera Comisar\u00eda de Chile Chico logr\u00f3 ubicar a un imputado de 82 a\u00f1os de edad, quien se manten\u00eda pr\u00f3fugo desde el a\u00f1o 2023, luego de que el Ministerio P\u00fablico lo acusara como autor del delito de abuso sexual reiterado infantil en contra de su bisnieta, quien en la \u00e9poca de los hechos era menor de 14 a\u00f1os de edad\u201d.<\/p>\n<p>La Fiscal Leiva a\u00f1adi\u00f3 que \u201cen raz\u00f3n de ello, el d\u00eda de hoy fue controlada su detenci\u00f3n, oportunidad en la que el Ministerio P\u00fablico solicit\u00f3 la prisi\u00f3n preventiva del imputado, accedi\u00e9ndose a dicha solicitud por parte del Tribunal, entendiendo que exist\u00eda un peligro para la seguridad de la sociedad en la libertad del imputado, as\u00ed como tambi\u00e9n un peligro de fuga\u201d.<\/p>\n<p>La persecutora penal agreg\u00f3 que \u201cen atenci\u00f3n a la etapa procesal en la que nos encontramos, el Tribunal fij\u00f3 una fecha pr\u00f3xima para efectos de preparar el juicio oral\u201d.<\/p>\n<p>La investigaci\u00f3n de este caso est\u00e1 a cargo de la Fiscal\u00eda Local de Chile Chico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras solicitud del Ministerio P\u00fablico, el Juzgado de Garant\u00eda de Chile Chico control\u00f3 la detenci\u00f3n de un imputado que permanec\u00eda pr\u00f3fugo de la justicia por delitos sexuales, el cual fue detenido por personal de Carabineros. Seg\u00fan explic\u00f3 la Fiscal Jefe de Cochrane y Chile Chico, Estefan\u00eda Leiva, el \u201c12 de marzo del a\u00f1o 2026, personal [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24808,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-24810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2026\/03\/mediapiaiextstaticimg_webpFiscaliaTribunalChileChicoimputadosolicitudMinisterio_source-scaled.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=24810"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24810\/revisions"}],"predecessor-version":[{"id":24811,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24810\/revisions\/24811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/24808"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=24810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=24810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=24810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}