{"id":24806,"date":"2026-03-13T12:59:01","date_gmt":"2026-03-13T15:59:01","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=24806"},"modified":"2026-03-13T12:59:01","modified_gmt":"2026-03-13T15:59:01","slug":"illapel-fiscalia-investiga-con-carabineros-un-cuasidelito-de-homicidio-en-que-motociclista-perdio-la-vida","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2026\/03\/13\/illapel-fiscalia-investiga-con-carabineros-un-cuasidelito-de-homicidio-en-que-motociclista-perdio-la-vida\/","title":{"rendered":"Illapel: Fiscal\u00eda investiga con Carabineros un cuasidelito de homicidio en que motociclista perdi\u00f3 la vida"},"content":{"rendered":"<p>La Fiscal\u00eda de Illapel investiga junto con Carabineros de Chile la muerte de un motociclista ocurrida en la comuna el 9 de marzo reci\u00e9n pasado.<\/p>\n<p>En los hechos est\u00e1 involucrado el conductor de una camioneta, quien fue formalizado por cuasidelito de homicidio, \u201cteniendo en consideraci\u00f3n los antecedentes recopilados por personal de Carabineros y de la Secci\u00f3n de Investigaciones de Accidentes de Tr\u00e1nsito, SIAT de la misma polic\u00eda\u201d, dijo Cristi\u00e1n Arcos, abogado de la fiscal\u00eda local de Illapel.<\/p>\n<p>\u201cEl personal se constituy\u00f3 en el sitio del suceso y entregaron un pre informe sobre la causa basal\u201d, agreg\u00f3 Arcos.<\/p>\n<p>Tras la imputaci\u00f3n, el conductor de la camioneta qued\u00f3 con medidas cautelares de arraigo nacional y el Juzgado de Garant\u00eda de Illapel concedi\u00f3 120 d\u00edas para el desarrollo de las diligencias de investigaci\u00f3n.<\/p>\n<p>\u201cSe est\u00e1n desarrollando m\u00e1s diligencias por parte del personal especializado y no se descarta ninguna hip\u00f3tesis\u201d, puntualiz\u00f3 el abogado Arcos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda de Illapel investiga junto con Carabineros de Chile la muerte de un motociclista ocurrida en la comuna el 9 de marzo reci\u00e9n pasado. En los hechos est\u00e1 involucrado el conductor de una camioneta, quien fue formalizado por cuasidelito de homicidio, \u201cteniendo en consideraci\u00f3n los antecedentes recopilados por personal de Carabineros y de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24805,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-24806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2026\/03\/mediapiaiextstaticimg_webpIllapelFiscaliaIllapelCarabinerospersonalArcos_source.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=24806"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24806\/revisions"}],"predecessor-version":[{"id":24807,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24806\/revisions\/24807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/24805"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=24806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=24806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=24806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}