{"id":24793,"date":"2026-03-13T08:09:55","date_gmt":"2026-03-13T11:09:55","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=24793"},"modified":"2026-03-13T08:09:55","modified_gmt":"2026-03-13T11:09:55","slug":"kast-considera-indultar-a-carabineros-condenados","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2026\/03\/13\/kast-considera-indultar-a-carabineros-condenados\/","title":{"rendered":"Kast considera indultar a carabineros condenados."},"content":{"rendered":"<p>El presidente Jos\u00e9 Antonio Kast aborda la posibilidad de indultar carabineros y militares condenados por delitos relacionados con el estallido social. Kast confirma que est\u00e1 estudiando distintos casos de agentes del Estado que fueron condenados en ese contexto. El jefe de Estado fue consultado por parlamentarios de su sector que han solicitado indultos en estos casos.<\/p>\n<p>Kast asegur\u00f3 en entrevista con T13 que est\u00e1n revisando cada situaci\u00f3n de manera particular. Indic\u00f3 que existe una apreciaci\u00f3n distinta a veces en temas judiciales, pero que son revisables. &#8220;La facultad de indulto es una facultad que hasta el d\u00eda de hoy tiene el Presidente de la Rep\u00fablica y yo la voy a utilizar&#8221;, enfatiz\u00f3 Kast.<\/p>\n<p>Del mismo modo, el jefe de Estado se\u00f1al\u00f3 que est\u00e1n estudiando cada caso y que avanzar\u00e1n en esa l\u00ednea para recuperar la paz con di\u00e1logo. Kast expres\u00f3 que entiende que alguien que haya sido v\u00edctima de una situaci\u00f3n como esa le cueste mucho superar. Sin embargo, invit\u00f3 a mirar lo que ha sucedido en otros pa\u00edses y en nuestra historia, se\u00f1alando la necesidad de perdonar.<\/p>\n<p>Recordemos que durante la administraci\u00f3n de Gabriel Boric, se indult\u00f3 a una decena de personas condenadas por delitos relacionados a las protestas. La diferencia entre ambos procesos radica en que los beneficiados en aquella ocasi\u00f3n no pertenec\u00edan a las fuerzas de orden y seguridad. Kast ahora pone el foco en uniformados que actuaron bajo mandato estatal.<\/p>\n<p><small><i><strong>Aviso de transparencia:<\/strong> Este art\u00edculo ha sido elaborado con la asistencia de Inteligencia Artificial para optimizar el procesamiento de informaci\u00f3n. Sin embargo, todo el contenido ha sido revisado, editado y validado por el equipo period\u00edstico de <strong><a href=\"https:\/\/laserenaradio.cl\/web\/\">LaSerenaRadio.cl<\/a><\/strong>, garantizando nuestra l\u00ednea editorial y veracidad informativa.<\/i><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Jos\u00e9 Antonio Kast aborda la posibilidad de indultar carabineros y militares condenados por delitos relacionados con el estallido social. Kast confirma que est\u00e1 estudiando distintos casos de agentes del Estado que fueron condenados en ese contexto. El jefe de Estado fue consultado por parlamentarios de su sector que han solicitado indultos en estos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24792,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-24793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2026\/03\/mediapiaiextstaticimg_webpayudaCubaKastpresidente_0-1.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=24793"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24793\/revisions"}],"predecessor-version":[{"id":24794,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24793\/revisions\/24794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/24792"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=24793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=24793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=24793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}