{"id":24745,"date":"2026-03-12T16:09:41","date_gmt":"2026-03-12T19:09:41","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=24745"},"modified":"2026-03-12T16:09:41","modified_gmt":"2026-03-12T19:09:41","slug":"emiten-un-aviso-por-precipitaciones-normales-a-moderadas-en-zonas-de-las-regiones-de-la-araucania-los-rios-y-los-lagos","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2026\/03\/12\/emiten-un-aviso-por-precipitaciones-normales-a-moderadas-en-zonas-de-las-regiones-de-la-araucania-los-rios-y-los-lagos\/","title":{"rendered":"Emiten un Aviso por Precipitaciones Normales a Moderadas en zonas de las regiones de La Araucan\u00eda, Los R\u00edos y Los Lagos"},"content":{"rendered":"<p>Desde la Direcci\u00f3n Meteorol\u00f3gica de Chile, emitieron el Aviso A112-2\/2026 por Precipitaciones debido a la condici\u00f3n sin\u00f3ptica Sistema frontal.<\/p>\n<p>En detalle, la <a href=\"http:\/\/www.meteochile.gob.cl\/PortalDMC-web\/index.xhtml\" rel=\"nofollow\">Direcci\u00f3n Meteorol\u00f3gica de Chile<\/a>, indica que este fen\u00f3meno se encontrar\u00e1 vigente desde <strong>la madrugada del s\u00e1bado 14 de marzo del 2026<\/strong> y hasta <strong>la madrugada del domingo 15 de marzo del 2026<\/strong>.<\/p>\n<p>Las zonas afectadas por la condici\u00f3n ser\u00edan: La Araucan\u00eda (Precordillera, Cordillera)<br \/>Los R\u00edos (Litoral, Cordillera Costa, Precordillera, Cordillera)<br \/>Los Lagos (Litoral, Cordillera Costa, Precordillera, Cordillera, Litoral Interior, Cordillera Austral, Patagonia Subandina)<\/p>\n<p>Debido a esta condici\u00f3n, se llama a tener precauci\u00f3n y cautela por el Aviso vigente por Precipitaciones Normales a Moderadas en zonas de las regiones de La Araucan\u00eda, Los R\u00edos y Los Lagos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la Direcci\u00f3n Meteorol\u00f3gica de Chile, emitieron el Aviso A112-2\/2026 por Precipitaciones debido a la condici\u00f3n sin\u00f3ptica Sistema frontal. En detalle, la Direcci\u00f3n Meteorol\u00f3gica de Chile, indica que este fen\u00f3meno se encontrar\u00e1 vigente desde la madrugada del s\u00e1bado 14 de marzo del 2026 y hasta la madrugada del domingo 15 de marzo del 2026. Las [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24744,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-24745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2026\/03\/mediapiaiextstaticimg_webpEmitenAlerta_1-1-scaled.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=24745"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24745\/revisions"}],"predecessor-version":[{"id":24746,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24745\/revisions\/24746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/24744"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=24745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=24745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=24745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}