{"id":24637,"date":"2026-03-10T08:22:50","date_gmt":"2026-03-10T11:22:50","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=24637"},"modified":"2026-03-10T08:22:50","modified_gmt":"2026-03-10T11:22:50","slug":"sismo-de-menor-intensidad-3-0-se-percibio-a-29-km-al-no-de-punta-de-choros","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2026\/03\/10\/sismo-de-menor-intensidad-3-0-se-percibio-a-29-km-al-no-de-punta-de-choros\/","title":{"rendered":"Sismo de menor intensidad 3.0 se percibi\u00f3 a 29 km al NO de Punta de Choros"},"content":{"rendered":"<p>Un movimiento s\u00edsmico ha sido registrado a las 03:03 horas (hora local).<\/p>\n<p>De acuerdo a la informaci\u00f3n oficial proporcionada por el <a href=\"https:\/\/www.sismologia.cl\/\" rel=\"nofollow\" target=\"_blank\">Centro Sismol\u00f3gico Nacional<\/a>, el evento tel\u00farico tuvo una magnitud de 3.0 Mlv grados.<\/p>\n<p>El epicentro fue localizado a 29 km al NO de Punta de Choros, con una profundidad de 31 km.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un movimiento s\u00edsmico ha sido registrado a las 03:03 horas (hora local). De acuerdo a la informaci\u00f3n oficial proporcionada por el Centro Sismol\u00f3gico Nacional, el evento tel\u00farico tuvo una magnitud de 3.0 Mlv grados. El epicentro fue localizado a 29 km al NO de Punta de Choros, con una profundidad de 31 km.<\/p>\n","protected":false},"author":2,"featured_media":24636,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-24637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2026\/03\/mediapiaiextstaticimg_sismossismo_20260310030323.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=24637"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24637\/revisions"}],"predecessor-version":[{"id":24638,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24637\/revisions\/24638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/24636"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=24637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=24637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=24637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}