{"id":24595,"date":"2026-03-09T17:23:13","date_gmt":"2026-03-09T20:23:13","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=24595"},"modified":"2026-03-09T17:23:13","modified_gmt":"2026-03-09T20:23:13","slug":"emiten-un-aviso-por-altas-temperaturas-en-zonas-desde-la-region-de-coquimbo-a-la-region-del-maule-2","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2026\/03\/09\/emiten-un-aviso-por-altas-temperaturas-en-zonas-desde-la-region-de-coquimbo-a-la-region-del-maule-2\/","title":{"rendered":"Emiten un Aviso por Altas Temperaturas en zonas desde la regi\u00f3n de Coquimbo a la regi\u00f3n del Maule"},"content":{"rendered":"<p>Desde la Direcci\u00f3n Meteorol\u00f3gica de Chile, emitieron el Aviso A104-1\/2026 por Altas Temperaturas debido a la condici\u00f3n sin\u00f3ptica Dorsal en altura.<\/p>\n<p>En detalle, la <a href=\"http:\/\/www.meteochile.gob.cl\/PortalDMC-web\/index.xhtml\" rel=\"nofollow\">Direcci\u00f3n Meteorol\u00f3gica de Chile<\/a>, indica que este fen\u00f3meno se encontrar\u00e1 vigente desde <strong>la ma\u00f1ana del martes 10 de marzo del 2026<\/strong> y hasta <strong>la tarde del martes 10 de marzo del 2026<\/strong>.<\/p>\n<p>Las zonas afectadas por la condici\u00f3n ser\u00edan: <\/p>\n<p>Coquimbo (Cordillera Costa, Precordillera y valles precordilleranos)<br \/>Valpara\u00edso (Litoral, Cordillera Costa)<br \/>Metropolitana (Cordillera Costa, Valle)<br \/>O&#8217;Higgins (Cordillera Costa, Valle)<br \/>Maule (Cordillera Costa, Valle)<\/p>\n<p>Debido a esta condici\u00f3n, se llama a tener precauci\u00f3n y cautela por el Aviso vigente por Altas Temperaturas en zonas desde la regi\u00f3n de Coquimbo a la regi\u00f3n del Maule.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la Direcci\u00f3n Meteorol\u00f3gica de Chile, emitieron el Aviso A104-1\/2026 por Altas Temperaturas debido a la condici\u00f3n sin\u00f3ptica Dorsal en altura. En detalle, la Direcci\u00f3n Meteorol\u00f3gica de Chile, indica que este fen\u00f3meno se encontrar\u00e1 vigente desde la ma\u00f1ana del martes 10 de marzo del 2026 y hasta la tarde del martes 10 de marzo del [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24594,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-24595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2026\/03\/mediapiaiextstaticimg_webpCordilleraCostabrAvisoAltasTemperaturas_1.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=24595"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24595\/revisions"}],"predecessor-version":[{"id":24596,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/24595\/revisions\/24596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/24594"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=24595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=24595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=24595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}