{"id":21720,"date":"2025-12-09T12:27:36","date_gmt":"2025-12-09T15:27:36","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=21720"},"modified":"2025-12-09T12:27:36","modified_gmt":"2025-12-09T15:27:36","slug":"charles-aranguiz-gano-jugador-crack-2025","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/12\/09\/charles-aranguiz-gano-jugador-crack-2025\/","title":{"rendered":"Charles Ar\u00e1nguiz gan\u00f3 Jugador Crack 2025"},"content":{"rendered":"<p>El f\u00fatbol chileno vivi\u00f3 su jornada m\u00e1s elegante y esperada: la Gala Crack 2025 de TNT Sports. Una alfombra roja repleta de figuras, un escenario armado para celebrar el final de temporada y la misi\u00f3n de reconocer a los mejores jugadores del a\u00f1o en el balompi\u00e9 nacional.<\/p>\n<p>Uno de los momentos m\u00e1s esperados lleg\u00f3 con el anuncio del premio al Jugador Crack, el galard\u00f3n reservado para el futbolista m\u00e1s determinante del pa\u00eds. El nombre elegido fue Charles Ar\u00e1nguiz, hist\u00f3rico mediocampista de Universidad de Chile y bicampe\u00f3n de Am\u00e9rica con La Roja.<\/p>\n<p>Aunque el volante no asisti\u00f3 a la Gala, hab\u00eda manifestado su rechazo a la gesti\u00f3n de la ANFP hacia los azules en 2025, dejando en claro que no asistir\u00eda al evento. &#8220;No tengo ganas de verle la cara a la dirigencia (de la ANFP), al Sifup. Me he sentido pasado a llevar. No tengo ganas de ir&#8221;, dijo el pasado 2 de diciembre.<\/p>\n<p>Finalmente, ning\u00fan integrante del plantel azul dijo presente en la ceremonia. Aunque no hubo palabras p\u00fablicas de Charles en la gala, los n\u00fameros hablaron por \u00e9l. En una temporada donde la experiencia fue clave, Ar\u00e1nguiz disput\u00f3 25 partidos de la Liga de Primera, anotando seis goles y sumando cuatro asistencias.<\/p>\n<p>A sus 36 a\u00f1os, el mediocampista demostr\u00f3 que, a pesar de su edad, sigue siendo uno de los futbolistas m\u00e1s completos y determinantes de la liga. Su presencia en el medio campo de La U no solo garantizaba control y din\u00e1mica, sino tambi\u00e9n ese toque de magia que lo hace \u00fanico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El f\u00fatbol chileno vivi\u00f3 su jornada m\u00e1s elegante y esperada: la Gala Crack 2025 de TNT Sports. Una alfombra roja repleta de figuras, un escenario armado para celebrar el final de temporada y la misi\u00f3n de reconocer a los mejores jugadores del a\u00f1o en el balompi\u00e9 nacional. Uno de los momentos m\u00e1s esperados lleg\u00f3 con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21719,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-21720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/12\/mediapiaiextstaticimg_webpCharlesAranguiz_1.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=21720"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21720\/revisions"}],"predecessor-version":[{"id":21721,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21720\/revisions\/21721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/21719"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=21720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=21720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=21720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}