{"id":21493,"date":"2025-12-06T23:08:09","date_gmt":"2025-12-07T02:08:09","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=21493"},"modified":"2025-12-06T23:08:09","modified_gmt":"2025-12-07T02:08:09","slug":"inter-miami-se-proclama-campeon-de-la-mls-por-primera-vez","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/12\/06\/inter-miami-se-proclama-campeon-de-la-mls-por-primera-vez\/","title":{"rendered":"Inter Miami se proclama campe\u00f3n de la MLS por primera vez"},"content":{"rendered":"<p>El Inter Miami se proclam\u00f3 campe\u00f3n de la Major Soccer League (MLS) por primera vez en su corta historia como club al superar (3-1) al Vancouver Whitecaps en la final de la MLS Cup 2025.<\/p>\n<p>Un t\u00edtulo que puso fin a la larga y exitosa carrera de los internacionales espa\u00f1oles Jordi Alba y Sergio Busquets. Leo Messi asisti\u00f3 en la segunda parte a los goles de Rodrigo de Paul y Tadeo Allende para cumplir el sue\u00f1o del Inter Miami de David Beckham en su sexta temporada.<\/p>\n<p>Los locales se fueron al descanso con el 1-0 de Edier Ocampo en propia puerta, pero a la hora de encuentro Ali Ahmed empat\u00f3 para los Whitecaps. El Chase Stadium se despidi\u00f3 como casa de los de Miami, que estrenar\u00e1n en 2026 el Miami Freedom Park.<\/p>\n<p>El club de Florida, que renov\u00f3 en octubre a Messi hasta 2028, hab\u00eda sido el mejor club de fase regular en 2024 y gan\u00f3 la Copa de la Liga en 2023. Con Javier Mascherano en su banquillo, Inter Miami hizo historia, tambi\u00e9n Messi con su trofeo 47, en el adi\u00f3s de dos leyendas de Espa\u00f1a y el FC Barcelona como Alba y Busquets.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Inter Miami se proclam\u00f3 campe\u00f3n de la Major Soccer League (MLS) por primera vez en su corta historia como club al superar (3-1) al Vancouver Whitecaps en la final de la MLS Cup 2025. Un t\u00edtulo que puso fin a la larga y exitosa carrera de los internacionales espa\u00f1oles Jordi Alba y Sergio Busquets. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21492,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-21493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/12\/homepiaiextractoscrapimg_webpclubInterMiamiprimeravez_1.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=21493"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21493\/revisions"}],"predecessor-version":[{"id":21494,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21493\/revisions\/21494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/21492"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=21493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=21493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=21493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}