{"id":21355,"date":"2025-11-30T21:10:01","date_gmt":"2025-12-01T00:10:01","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=21355"},"modified":"2025-11-30T21:10:01","modified_gmt":"2025-12-01T00:10:01","slug":"manuel-pellegrini-se-muestra-satisfecho-tras-victoria-del-betis-ante-sevilla","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/11\/30\/manuel-pellegrini-se-muestra-satisfecho-tras-victoria-del-betis-ante-sevilla\/","title":{"rendered":"Manuel Pellegrini se muestra satisfecho tras victoria del Betis ante Sevilla."},"content":{"rendered":"<p>Manuel Pellegrini, entrenador del Betis, mostr\u00f3 su satisfacci\u00f3n tras la victoria por 0-2 ante el Sevilla, destacando un \u201cbuen partido en la fase defensiva\u201d. Adem\u00e1s, critic\u00f3 con firmeza a los hinchas sevillanos que lanzaron proyectiles durante el encuentro. <\/p>\n<p>Incidentes que ocurrieron cuando restaban cuatro minutos de juego y obligaron al \u00e1rbitro a suspender el partido por 15 minutos. Sobre la suspensi\u00f3n, Pellegrini reconoci\u00f3 que no la quer\u00edan \u201cporque quedaban dos o tres minutos\u201d y \u201cera mucho peor ir para adentro\u201d. <\/p>\n<p>Empezaron a caer todo tipo de proyectiles dentro del terreno de juego. Tiene que haber una rivalidad deportiva, creo que no es correcto empezar a tirar objetos. El \u00e1rbitro dijo que reglamentariamente no pod\u00edamos seguir. No pas\u00f3 despu\u00e9s nada y supimos mantener el resultado: el triunfo, dedicado a toda la gente del Betis, que se lo merec\u00eda.<\/p>\n<p>Respecto al partido en particular, victoria gracias a los tantos de Pablo Fornals (54\u2032) y Sergi Altimira (68\u2032). Dijo que \u201cel derbi es el derbi. Normalmente son partidos de esa naturaleza, ninguno quiere cometer errores\u201d. <\/p>\n<p>Explic\u00f3 que en el segundo tiempo bajaron \u201cun poco las revoluciones\u201d, hicieron dos goles y tuvieron \u201cm\u00e1s opciones\u201d que los del argentino Mat\u00edas Almeyda.<\/p>\n<p>Tuvimos cuatro bajas muy importantes, lo dijimos antes, hay un plantel y nunca nos lamentamos por los que no est\u00e1n si no que exigimos a los que est\u00e1n. Dijo que \u201cel plantel est\u00e1 muy comprometido e involucrado\u201d y \u201cno hay equipo A y equipo B: partido a partido vamos intentando ver qui\u00e9nes est\u00e1n mejor\u201d. Me gust\u00f3 mucho la personalidad del equipo\u201d, mantuvo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manuel Pellegrini, entrenador del Betis, mostr\u00f3 su satisfacci\u00f3n tras la victoria por 0-2 ante el Sevilla, destacando un \u201cbuen partido en la fase defensiva\u201d. Adem\u00e1s, critic\u00f3 con firmeza a los hinchas sevillanos que lanzaron proyectiles durante el encuentro. Incidentes que ocurrieron cuando restaban cuatro minutos de juego y obligaron al \u00e1rbitro a suspender el partido [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21354,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-21355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/11\/homepiaiextractoscrapimg_predeterminadalaserenaradio_deportes-8.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=21355"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21355\/revisions"}],"predecessor-version":[{"id":21356,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21355\/revisions\/21356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/21354"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=21355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=21355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=21355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}