{"id":21164,"date":"2025-11-23T22:41:37","date_gmt":"2025-11-24T01:41:37","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=21164"},"modified":"2025-11-23T22:41:37","modified_gmt":"2025-11-24T01:41:37","slug":"el-arsenal-golea-al-tottenham-y-se-coloca-lider-de-la-premier-league","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/11\/23\/el-arsenal-golea-al-tottenham-y-se-coloca-lider-de-la-premier-league\/","title":{"rendered":"El Arsenal golea al Tottenham y se coloca l\u00edder de la Premier League."},"content":{"rendered":"<p>El Arsenal domin\u00f3 el derbi del Norte de Londres contra el Tottenham Hotspur gracias al &#8216;hat trick&#8217; de Eberechi Eze. Con esta victoria, los &#8216;Gunners&#8217; ampl\u00edan la ventaja en la cima a seis puntos sobre el Chelsea y siete sobre el Manchester City, permiti\u00e9ndoles so\u00f1ar con su primera Premier League en m\u00e1s de dos d\u00e9cadas.<\/p>\n<p>Eberechi Eze fue estrella del encuentro, metiendo tres goles que sentenciaron la victoria. En apenas cinco minutos, Eze castig\u00f3 al Tottenham, completamente maniatados con un esquema defensivo y metido atr\u00e1s. El &#8217;10&#8217; del Arsenal aprovech\u00f3 una gran jugada combinatoria para marcar el 3-0.<\/p>\n<p>Mientras tanto, el Tottenham sali\u00f3 con el plan equivocado. En una conducci\u00f3n en el centro del campo, Mart\u00edn Zubimendi cometi\u00f3 un error que dej\u00f3 libre la pelota a Richarlison y Palhinha, quienes anotaron un golazo desde m\u00e1s de cuarenta metros.<\/p>\n<p>Los &#8216;Spurs&#8217; intentaron recortar distancias, pero su primer tiro fue in\u00fatil. En una triangulaci\u00f3n entre Merino, Trossard y Eze, el mediapunta marc\u00f3 su primer &#8216;hat trick&#8217; con la camiseta del Arsenal en su primer derbi del Norte de Londres.<\/p>\n<p>El Arsenal fortalece su posici\u00f3n de l\u00edder con 29 puntos, superando al Chelsea (23) y al Manchester City (22). El Tottenham se queda noveno, con 18 unidades, a tres de la Champions League.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Arsenal domin\u00f3 el derbi del Norte de Londres contra el Tottenham Hotspur gracias al &#8216;hat trick&#8217; de Eberechi Eze. Con esta victoria, los &#8216;Gunners&#8217; ampl\u00edan la ventaja en la cima a seis puntos sobre el Chelsea y siete sobre el Manchester City, permiti\u00e9ndoles so\u00f1ar con su primera Premier League en m\u00e1s de dos d\u00e9cadas. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21163,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-21164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/11\/homepiaiextractoscrapimg_webpArsenalTottenham_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=21164"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21164\/revisions"}],"predecessor-version":[{"id":21165,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21164\/revisions\/21165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/21163"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=21164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=21164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=21164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}