{"id":21094,"date":"2025-11-21T22:36:24","date_gmt":"2025-11-22T01:36:24","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=21094"},"modified":"2025-11-21T22:36:24","modified_gmt":"2025-11-22T01:36:24","slug":"ironman-70-3-valdivia-deportistas-internacionales-llegaran-a-la-region-de-los-rios","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/11\/21\/ironman-70-3-valdivia-deportistas-internacionales-llegaran-a-la-region-de-los-rios\/","title":{"rendered":"Ironman 70.3 Valdivia: deportistas internacionales llegar\u00e1n a la regi\u00f3n de Los R\u00edos."},"content":{"rendered":"<p>Valdivia prepara su Ironman 70.3 para este 30 de noviembre, reuniendo destacados atletas de \u00e9lite nacionales e internacionales. El evento deportivo se celebra en la capital de la regi\u00f3n de Los R\u00edos, con marcas y comercio local a la espera del gran d\u00eda.<\/p>\n<p>En entrevista, Fernanda Castro, directora del Ironman 70.3, mencion\u00f3 que la organizaci\u00f3n lleva un a\u00f1o preparando una edici\u00f3n que pretende consolidarse como la m\u00e1s importante en el sur del pa\u00eds. En la \u00e9lite masculina destaca el regreso del vigente campe\u00f3n, Colin Szuch (Sach), junto a Mart\u00edn Ulloa y Diego Moya, quien debutar\u00e1 en esta distancia.<\/p>\n<p>En la categor\u00eda femenina, Macarena Salazar buscar\u00e1 defendiendo su t\u00edtulo contra competidoras de Argentina, M\u00e9xico, Francia, Gran Breta\u00f1a y Canad\u00e1. La destacada B\u00e1rbara Riveros tambi\u00e9n participar\u00e1, aspirando a un lugar en el podio. Valdivia recibir\u00e1 40 cupos para deportistas locales, mientras que M\u00e1fil y San Jos\u00e9 de la Mariquina sumar\u00e1n representantes en el circuito ciclista.<\/p>\n<p>El evento genera un impacto econ\u00f3mico significativo. Seg\u00fan Castro, el Ironman del a\u00f1o pasado dej\u00f3 cerca de 5 millones de d\u00f3lares, y la capacidad hotelera est\u00e1 al 100% para esta edici\u00f3n. Se destaca el Pasaporte Naranja, que ofrece descuentos en restaurantes locales a trav\u00e9s de una alianza con el Banco Ita\u00fa.<\/p>\n<p>La directora destac\u00f3 los mejores puntos para seguir la competencia: el Puente Cau-Cau para observar las diferentes disciplinas, la Costanera ideal para ver tres giros de trote y el Parque Saval como zona de transici\u00f3n entre nataci\u00f3n y ciclismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valdivia prepara su Ironman 70.3 para este 30 de noviembre, reuniendo destacados atletas de \u00e9lite nacionales e internacionales. El evento deportivo se celebra en la capital de la regi\u00f3n de Los R\u00edos, con marcas y comercio local a la espera del gran d\u00eda. En entrevista, Fernanda Castro, directora del Ironman 70.3, mencion\u00f3 que la organizaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21093,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-21094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/11\/homepiaiextractoscrapimg_predeterminadalaserenaradio_deportes-5.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=21094"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21094\/revisions"}],"predecessor-version":[{"id":21095,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/21094\/revisions\/21095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/21093"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=21094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=21094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=21094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}