{"id":20959,"date":"2025-11-17T23:30:59","date_gmt":"2025-11-18T02:30:59","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=20959"},"modified":"2025-11-17T23:30:59","modified_gmt":"2025-11-18T02:30:59","slug":"jeannette-jara-preve-sumar-propuestas-para-segunda-vuelta-presidencial","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/11\/17\/jeannette-jara-preve-sumar-propuestas-para-segunda-vuelta-presidencial\/","title":{"rendered":"Jeannette Jara prev\u00e9 sumar propuestas para segunda vuelta presidencial."},"content":{"rendered":"<p>Jeannette Jara, candidata presidencial de Unidad por Chile y la DC, avanz\u00f3 a segunda vuelta y se\u00f1al\u00f3 la intenci\u00f3n de sumar propuestas de Evelyn Matthei y Franco Parisi. En una conferencia en La Pintana, la abanderada expres\u00f3 su satisfacci\u00f3n por el resultado electoral, destacando que sus cambios son complementarios a su estrategia exitosa.<\/p>\n<p>\u201cVamos a incorporar algunas propuestas, pero mantendremos fundamentalmente nuestro equipo de trabajo, que ha funcionado bien hasta ahora\u201d, asegur\u00f3 Jara. Sobre Jos\u00e9 Antonio Kast y las acusaciones del oficialismo, la candidata sostuvo: \u201cEncuentro que es una persona autoritaria, que no tolera a aquellos con ideas distintas\u201d. Asegur\u00f3 que su camino hacia la presidencia ha sido siempre dif\u00edcil, pero encuentra motivaci\u00f3n en los desaf\u00edos importantes.<\/p>\n<p>En cuanto al potencial apoyo de votantes de Franco Parisi, Jara valor\u00f3 la estrategia del l\u00edder del PDG. \u201cYo voy a trabajar por conquistar a la ciudadan\u00eda y respetar el \u00e9xito obtenido por \u00e9l\u201d, afirm\u00f3. Indic\u00f3 que considerar\u00e1 reunirse con otros candidatos para discutir propuestas.<\/p>\n<p>\u201cS\u00ed, tendr\u00e9 en cuenta varias buenas ideas de los otros candidatos presidenciales. Comenzaremos por la propuesta de Evelyn Matthei sobre oncol\u00f3gico y la del IVA en medicamentos de Franco Parisi\u201d, agreg\u00f3 Jara. Se comprometi\u00f3 a explorar posibilidades de conversaciones con t\u00e9cnicos de ambos para evaluar si hay espacio para colaboraci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeannette Jara, candidata presidencial de Unidad por Chile y la DC, avanz\u00f3 a segunda vuelta y se\u00f1al\u00f3 la intenci\u00f3n de sumar propuestas de Evelyn Matthei y Franco Parisi. En una conferencia en La Pintana, la abanderada expres\u00f3 su satisfacci\u00f3n por el resultado electoral, destacando que sus cambios son complementarios a su estrategia exitosa. \u201cVamos a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20958,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-20959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/11\/homepiaiextractoscrapimg_predeterminadalaserenaradio_politica-9.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=20959"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20959\/revisions"}],"predecessor-version":[{"id":20960,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20959\/revisions\/20960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/20958"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=20959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=20959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=20959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}