{"id":20761,"date":"2025-11-11T08:18:27","date_gmt":"2025-11-11T11:18:27","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=20761"},"modified":"2025-11-11T08:18:27","modified_gmt":"2025-11-11T11:18:27","slug":"kast-apoya-una-invasion-estadounidense-de-venezuela","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/11\/11\/kast-apoya-una-invasion-estadounidense-de-venezuela\/","title":{"rendered":"Kast apoya una invasi\u00f3n estadounidense de Venezuela."},"content":{"rendered":"<p>El candidato del Partido Republicano, Jos\u00e9 Antonio Kast, se mostr\u00f3 abierto a respaldar una eventual invasi\u00f3n \u2014por tierra\u2014 de Estados Unidos a Venezuela. <\/p>\n<p>Fue en el contexto del bloque de preguntas de gobernabilidad, durante el debate de Anatel, que los aspirantes a La Moneda fueron puestos ante esta situaci\u00f3n. <\/p>\n<p>Dos llamados surgieron: el primero, planteado por el presidente de Estados Unidos, Donald Trump, solicit\u00e1ndole su respaldo para invadir Venezuela; y el segundo, venido de Nicol\u00e1s Maduro, advirtiendo la situaci\u00f3n y pidiendo solidaridad con un gobierno latinoamericano.<\/p>\n<p>Al respecto, Kast contest\u00f3: &#8220;Yo s\u00ed le contestar\u00eda a Maduro y le dir\u00eda &#8216;v\u00e1yase. Deje su dictadura&#8217;. Despu\u00e9s le dir\u00eda al Presidente Trump: proceda&#8221;.<\/p>\n<p>Cuando se le pregunt\u00f3 si respaldar\u00eda esta \u00faltima acci\u00f3n, el presidenciable asinti\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El candidato del Partido Republicano, Jos\u00e9 Antonio Kast, se mostr\u00f3 abierto a respaldar una eventual invasi\u00f3n \u2014por tierra\u2014 de Estados Unidos a Venezuela. Fue en el contexto del bloque de preguntas de gobernabilidad, durante el debate de Anatel, que los aspirantes a La Moneda fueron puestos ante esta situaci\u00f3n. Dos llamados surgieron: el primero, planteado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20760,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-20761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/11\/homepiaiextractoscrapimg_webpKastVenezuela_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=20761"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20761\/revisions"}],"predecessor-version":[{"id":20762,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20761\/revisions\/20762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/20760"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=20761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=20761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=20761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}