{"id":20659,"date":"2025-11-07T17:40:40","date_gmt":"2025-11-07T20:40:40","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=20659"},"modified":"2025-11-07T17:40:40","modified_gmt":"2025-11-07T20:40:40","slug":"jeannette-jara-habla-sobre-las-cuentas-de-luz-y-acusacion-a-pardow","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/11\/07\/jeannette-jara-habla-sobre-las-cuentas-de-luz-y-acusacion-a-pardow\/","title":{"rendered":"Jeannette Jara habla sobre las cuentas de luz y acusaci\u00f3n a Pardow."},"content":{"rendered":"<p>Jeannette Jara, candidata del oficialismo a la Presidencia en entrevista con Radio B\u00edo B\u00edo, se refiri\u00f3 a la situaci\u00f3n del exministro de Energ\u00eda, Diego Pardow, por las cuentas de la luz, calific\u00e1ndola como &#8220;grave&#8221;. Sin embargo, descart\u00f3 apoyar una acusaci\u00f3n constitucional. <\/p>\n<p>Por la misma AC, Jara fue clara en decir que \u201ca lo mejor si \u00e9l hubiera seguido en el cargo s\u00ed, pero \u00e9l pag\u00f3 r\u00e1pidamente sus responsabilidades pol\u00edticas. Yo creo que son cosas distintas\u201d. <\/p>\n<p>Primero, la situaci\u00f3n la encuentro grave, francamente, a m\u00ed me molest\u00f3 de fondo, porque s\u00e9 lo que cuesta pagar la luz, me imagino a la gente lo que le debi\u00f3 haber costado. Adem\u00e1s, esto influy\u00f3 en el mismo IPC.<\/p>\n<p>Recordemos que diputados de Dem\u00f3cratas solicitaron al presidente de la C\u00e1mara que priorice el debate y la votaci\u00f3n de la AC, antes de la primera vuelta presidencial, es decir, la pr\u00f3xima semana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeannette Jara, candidata del oficialismo a la Presidencia en entrevista con Radio B\u00edo B\u00edo, se refiri\u00f3 a la situaci\u00f3n del exministro de Energ\u00eda, Diego Pardow, por las cuentas de la luz, calific\u00e1ndola como &#8220;grave&#8221;. Sin embargo, descart\u00f3 apoyar una acusaci\u00f3n constitucional. Por la misma AC, Jara fue clara en decir que \u201ca lo mejor si [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20658,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-20659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/11\/homepiaiextractoscrapimg_webpluzJeannetteJaracuentasgrave_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=20659"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20659\/revisions"}],"predecessor-version":[{"id":20660,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20659\/revisions\/20660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/20658"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=20659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=20659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=20659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}