{"id":20629,"date":"2025-11-06T22:21:15","date_gmt":"2025-11-07T01:21:15","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=20629"},"modified":"2025-11-06T22:21:15","modified_gmt":"2025-11-07T01:21:15","slug":"cristiano-ronaldo-apoya-a-donald-trump-por-sus-acciones-humanitarias","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/11\/06\/cristiano-ronaldo-apoya-a-donald-trump-por-sus-acciones-humanitarias\/","title":{"rendered":"Cristiano Ronaldo apoya a Donald Trump por sus acciones humanitarias"},"content":{"rendered":"<p>El astro portugu\u00e9s Cristiano Ronaldo sorprendi\u00f3 al asegurar que el presidente de Estados Unidos, Donald Trump, \u201ces uno de los hombres que puede ayudar a cambiar el mundo\u201d, durante una entrevista con el presentador brit\u00e1nico Piers Morgan.<\/p>\n<p>As\u00ed lo adelantaron este martes en sus canales de YouTube el futbolista y el periodista. En la conversaci\u00f3n, Morgan le pregunt\u00f3 sobre el mensaje que dej\u00f3 Ronaldo al firmarle una camiseta a Trump, que le regal\u00f3 en junio pasado el presidente del Consejo Europeo, el portugu\u00e9s Antonio Costa.<\/p>\n<p>\u201cPara el presidente Donald Trump. Jugando por la paz\u201d, se le\u00eda en la prenda y Cristiano Ronaldo respondi\u00f3: \u201cEs uno de los hombres que puede ayudar a cambiar el mundo\u201d.<\/p>\n<p>Seg\u00fan el peque\u00f1o adelanto, en la parte dos del encuentro, el jugador del Al Nassr saud\u00ed rememorar\u00e1 su pasado y hablar\u00e1 sobre la muerte de su compa\u00f1ero de la selecci\u00f3n Diogo Jota, quien falleci\u00f3 este verano en un accidente de tr\u00e1fico junto a su hermano en una carretera espa\u00f1ola.<\/p>\n<p>Tambi\u00e9n reflexionar\u00e1 sobre el pr\u00f3ximo Mundial, que se disputar\u00e1 en Canad\u00e1, Estados Unidos y M\u00e9xico, y lo que supondr\u00e1 para su carrera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El astro portugu\u00e9s Cristiano Ronaldo sorprendi\u00f3 al asegurar que el presidente de Estados Unidos, Donald Trump, \u201ces uno de los hombres que puede ayudar a cambiar el mundo\u201d, durante una entrevista con el presentador brit\u00e1nico Piers Morgan. As\u00ed lo adelantaron este martes en sus canales de YouTube el futbolista y el periodista. En la conversaci\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20628,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-20629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/11\/homepiaiextractoscrapimg_predeterminadalaserenaradio_deportes-2.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=20629"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20629\/revisions"}],"predecessor-version":[{"id":20630,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20629\/revisions\/20630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/20628"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=20629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=20629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=20629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}