{"id":20560,"date":"2025-11-03T20:14:41","date_gmt":"2025-11-03T23:14:41","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=20560"},"modified":"2025-11-03T20:14:41","modified_gmt":"2025-11-03T23:14:41","slug":"johannes-kaiser-critica-al-servicio-medico-legal-sml-por-intervenir-politicamente-en-el-proceso-electoral","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/11\/03\/johannes-kaiser-critica-al-servicio-medico-legal-sml-por-intervenir-politicamente-en-el-proceso-electoral\/","title":{"rendered":"Johannes Kaiser critica al Servicio M\u00e9dico Legal (SML) por intervenir pol\u00edticamente en el proceso electoral"},"content":{"rendered":"<p>Johannes Kaiser, candidato presidencial del Partido Nacional Libertario, cuestion\u00f3 nuevamente al <a href=\"http:\/\/www.sml.gob.cl\/\">Servicio M\u00e9dico Legal<\/a> (SML), acus\u00e1ndolo de \u201cenga\u00f1ar a la opini\u00f3n p\u00fablica\u201d e intervenir pol\u00edticamente en el proceso electoral. Sus declaraciones se producen despu\u00e9s que el organismo negara la existencia de restos de presuntos detenidos desaparecidos en su poder, y justo cuando el gobierno calific\u00f3 como aberrantes las cr\u00edticas del candidato a La Moneda al Plan Nacional de B\u00fasqueda, cuestionamientos a los que m\u00e1s tarde se sum\u00f3 Evelyn Matthei. <\/p>\n<p>Kaiser solicit\u00f3 a la direcci\u00f3n del SML, con militancia en el PC, que dejaran de intervenir en esta elecci\u00f3n. Este conflicto comenz\u00f3 el s\u00e1bado cuando el aspirante a La Moneda critic\u00f3 el Plan Nacional de B\u00fasqueda de Personas Detenidas Desaparecidas, impulsado por el gobierno del Presidente Gabriel Boric, y cuestionamientos a los que m\u00e1s tarde se sum\u00f3 Evelyn Matthei.<\/p>\n<p>En ese d\u00eda, Kaiser se\u00f1al\u00f3 que \u201cel plan de b\u00fasqueda es una estafa\u201d y agreg\u00f3: \u201cUsted no puede empezar a buscar si usted no sabe lo que ya tiene\u201d. Esta acusaci\u00f3n fue respondida r\u00e1pidamente por el <a href=\"http:\/\/www.sml.gob.cl\/\">Servicio M\u00e9dico Legal<\/a> (SML), que neg\u00f3 la existencia de restos de presuntos detenidos desaparecidos en su poder, enfatizando: \u201cno existen en sus dependencias osamentas sin periciar\u201d.<\/p>\n<p>Luego de esta jornada, varios ministros del gabinete salieron a responder los cuestionamientos y defender el programa impulsado por el Gobierno. Kaiser redobl\u00f3 sus cr\u00edticas afirmando que tienen pruebas en video y en documentaci\u00f3n. Tambi\u00e9n indic\u00f3: \u201cPericiar no es lo mismo que identificar. Lo que no ha hecho el SML ha sido identificar los restos de cientos de detenidos desaparecidos que est\u00e1n en su poder, porque no hab\u00eda recibido la orden judicial para hacerlo\u201d. <\/p>\n<p>Sobre la decisi\u00f3n del Gobierno de cerrar el penal de Punta Peuco, Kaiser cuestion\u00f3 duramente la medida, calific\u00e1ndola como \u201crevanchista\u201d y argumentando: \u201cEst\u00e1 transformando un geri\u00e1trico \u2014porque es eso, un hospicio donde la gente se est\u00e1 muriendo\u2014 en una c\u00e1rcel com\u00fan. No s\u00e9 si la Corte Suprema se lo va a permitir o se lo va a aguantar, porque adem\u00e1s est\u00e1 cometiendo una violaci\u00f3n a los derechos humanos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Johannes Kaiser, candidato presidencial del Partido Nacional Libertario, cuestion\u00f3 nuevamente al Servicio M\u00e9dico Legal (SML), acus\u00e1ndolo de \u201cenga\u00f1ar a la opini\u00f3n p\u00fablica\u201d e intervenir pol\u00edticamente en el proceso electoral. Sus declaraciones se producen despu\u00e9s que el organismo negara la existencia de restos de presuntos detenidos desaparecidos en su poder, y justo cuando el gobierno calific\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20559,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-20560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/11\/homepiaiextractoscrapimg_webpKaisercandidatoServicioLegal_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=20560"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20560\/revisions"}],"predecessor-version":[{"id":20561,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20560\/revisions\/20561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/20559"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=20560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=20560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=20560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}