{"id":20551,"date":"2025-11-03T20:03:29","date_gmt":"2025-11-03T23:03:29","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=20551"},"modified":"2025-11-03T20:03:29","modified_gmt":"2025-11-03T23:03:29","slug":"cristiano-ronaldo-reafirma-su-superioridad-sobre-messi","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/11\/03\/cristiano-ronaldo-reafirma-su-superioridad-sobre-messi\/","title":{"rendered":"Cristiano Ronaldo reafirma su superioridad sobre Messi."},"content":{"rendered":"<p>La eterna discusi\u00f3n sobre qui\u00e9n ostenta el t\u00edtulo de mejor futbolista de todos los tiempos sigue generando controversia, y recientemente Cristiano Ronaldo reaviv\u00f3 el fuego al hacer unas declaraciones que no pasaron desapercibidas.<\/p>\n<p>En un adelanto de su entrevista con el periodista Piers Morgan, el astro portugu\u00e9s dej\u00f3 claro su punto de vista sobre su rivalidad con Lionel Messi. Cuando Morgan le pregunt\u00f3 directamente si Messi era mejor que \u00e9l, Ronaldo no dud\u00f3 ni un segundo: \u201c\u00bfMessi es mejor que yo? No estoy de acuerdo con esa opini\u00f3n. No quiero ser humilde\u201d.<\/p>\n<p>Con la seguridad que lo caracteriza, el delantero del Al Nassr reafirm\u00f3 que para \u00e9l, la comparaci\u00f3n con el argentino no tiene justificaci\u00f3n, dejando en claro que no teme expresar su opini\u00f3n sobre un tema tan debatido en el mundo del f\u00fatbol.<\/p>\n<p>En la misma charla, CR7 fue consultado sobre las opiniones pasadas de Wayne Rooney, su excompa\u00f1ero en el United, quien en su momento hab\u00eda afirmado que Messi estaba por encima del portugu\u00e9s. La respuesta de Cristiano fue igualmente directa: \u201cNo me supone ning\u00fan problema esas declaraciones\u201d.<\/p>\n<p>Durante la entrevista, Ronaldo tambi\u00e9n abord\u00f3 una reciente pol\u00e9mica sobre su fortuna personal. Tras los rumores que lo se\u00f1alaban como el \u201cprimer deportista multimillonario\u201d, el atacante se apresur\u00f3 a corregir la informaci\u00f3n: \u201cEso no es cierto, me convert\u00ed en multimillonario hace muchos a\u00f1os\u201d, asegur\u00f3, dejando claro que no es un tema reciente.<\/p>\n<p>Los n\u00fameros de Cristiano Ronaldo siguen siendo impresionantes y refuerzan su legado. Con 140 goles en la UEFA Champions League, 450 con el Real Madrid, 141 con la selecci\u00f3n de Portugal, y un palmar\u00e9s que incluye cinco Champions League, tres Premier League, dos t\u00edtulos en LaLiga, una Eurocopa y dos UEFA Nations League, el portugu\u00e9s ha demostrado su versatilidad y su capacidad para brillar en distintas competiciones y equipos.<\/p>\n<p>Por su parte, Messi tambi\u00e9n mantiene cifras deslumbrantes que refuerzan su propia leyenda. Con 672 goles con el FC Barcelona y 114 con la selecci\u00f3n argentina, el rosarino ha sumado 35 t\u00edtulos con el club catal\u00e1n y tres con la Albiceleste, destac\u00e1ndose especialmente por su reciente conquista de la Copa del Mundo 2022.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La eterna discusi\u00f3n sobre qui\u00e9n ostenta el t\u00edtulo de mejor futbolista de todos los tiempos sigue generando controversia, y recientemente Cristiano Ronaldo reaviv\u00f3 el fuego al hacer unas declaraciones que no pasaron desapercibidas. En un adelanto de su entrevista con el periodista Piers Morgan, el astro portugu\u00e9s dej\u00f3 claro su punto de vista sobre su [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20550,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-20551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/11\/homepiaiextractoscrapimg_predeterminadalaserenaradio_deportes-1.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=20551"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20551\/revisions"}],"predecessor-version":[{"id":20552,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20551\/revisions\/20552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/20550"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=20551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=20551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=20551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}