{"id":20318,"date":"2025-10-23T14:28:19","date_gmt":"2025-10-23T17:28:19","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=20318"},"modified":"2025-10-23T14:28:19","modified_gmt":"2025-10-23T17:28:19","slug":"kaiser-asegura-llegar-a-segunda-vuelta-presidencial","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/10\/23\/kaiser-asegura-llegar-a-segunda-vuelta-presidencial\/","title":{"rendered":"Kaiser asegura llegar a segunda vuelta presidencial"},"content":{"rendered":"<p>Johannes Kaiser, del Partido Nacional Libertario (PNL), optimista de alcanzar la segunda vuelta presidencial, reconoci\u00f3 la posibilidad de empate t\u00e9cnico con Jos\u00e9 Antonio Kast y Evelyn Matthei. En Temuco, regi\u00f3n de La Araucan\u00eda, Kaiser respondi\u00f3 a las inquietudes ciudadanas sobre el Estado de Excepci\u00f3n y propuso el Estado de Sitio para zonas espec\u00edficas como Temucuicui en Ercilla y Cerro Chu\u00f1o en Arica. Asegur\u00f3 que implementar\u00eda esta medida temporalmente para permitir operaciones armadas.<\/p>\n<p>El candidato presidencial enfatiz\u00f3 la importancia del Estado en sectores olvidados, prometiendo confrontar a terroristas y delincuentes con fuerza. Seg\u00fan Kaiser, su aumento en las encuestas se debe a ser un ant\u00eddoto frente al actual Gobierno, que no cumple sus expectativas.<\/p>\n<p>Kaiser mantiene su optimismo pese a la competencia, asegurando que no roba votos a Kast y matizando que el incremento de apoyo es debido a una percepci\u00f3n negativa hacia el gobierno en ejercicio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Johannes Kaiser, del Partido Nacional Libertario (PNL), optimista de alcanzar la segunda vuelta presidencial, reconoci\u00f3 la posibilidad de empate t\u00e9cnico con Jos\u00e9 Antonio Kast y Evelyn Matthei. En Temuco, regi\u00f3n de La Araucan\u00eda, Kaiser respondi\u00f3 a las inquietudes ciudadanas sobre el Estado de Excepci\u00f3n y propuso el Estado de Sitio para zonas espec\u00edficas como Temucuicui [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20317,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-20318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/10\/homepiaiextractoscrapimg_webppresidencialEstadosegunda_1.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=20318"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20318\/revisions"}],"predecessor-version":[{"id":20319,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20318\/revisions\/20319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/20317"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=20318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=20318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=20318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}