{"id":20312,"date":"2025-10-23T13:11:51","date_gmt":"2025-10-23T16:11:51","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=20312"},"modified":"2025-10-23T13:11:51","modified_gmt":"2025-10-23T16:11:51","slug":"el-frente-amplio-rechaza-la-acusacion-a-diego-pardow","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/10\/23\/el-frente-amplio-rechaza-la-acusacion-a-diego-pardow\/","title":{"rendered":"El Frente Amplio rechaza la acusaci\u00f3n a Diego Pardow."},"content":{"rendered":"<p>Jaime S\u00e1ez, jefe de bancada del Frente Amplio (FA), abord\u00f3 la inminente acusaci\u00f3n constitucional contra Diego Pardow, exministro de Energ\u00eda. Este representante reiter\u00f3 su rechazo a esta acci\u00f3n parlamentaria y calific\u00f3 la AC como una &#8220;maniobra electoral&#8221; que carece de sentido jur\u00eddico y pol\u00edtico.<\/p>\n<p>En conversaci\u00f3n con Emol, S\u00e1ez se\u00f1al\u00f3 que esta acusaci\u00f3n presenta un desaf\u00edo para el oficialismo y la Democracia Cristiana, al exigir mayor disciplina. Aunque distinta a las anteriores, ya que no ha habido declaraciones p\u00fablicas en conjunto de las oposiciones, S\u00e1ez advirti\u00f3 que este es un momento crucial en el contexto preelectoral.<\/p>\n<p>Sobre posibles impactos en la elecci\u00f3n de noviembre, el diputado S\u00e1ez coment\u00f3 que &#8220;obviamente es una situaci\u00f3n con la que es dif\u00edcil lidiar&#8221;. Sin embargo, se\u00f1al\u00f3 que m\u00e1s que complicaci\u00f3n pol\u00edtica, se trata de la circunstancia temporal y el enfrentamiento a una acusaci\u00f3n en un momento tan decisivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jaime S\u00e1ez, jefe de bancada del Frente Amplio (FA), abord\u00f3 la inminente acusaci\u00f3n constitucional contra Diego Pardow, exministro de Energ\u00eda. Este representante reiter\u00f3 su rechazo a esta acci\u00f3n parlamentaria y calific\u00f3 la AC como una &#8220;maniobra electoral&#8221; que carece de sentido jur\u00eddico y pol\u00edtico. En conversaci\u00f3n con Emol, S\u00e1ez se\u00f1al\u00f3 que esta acusaci\u00f3n presenta un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20311,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-20312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/10\/homepiaiextractoscrapimg_webpDiegoPardowmomentoJaimejefe_1.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=20312"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20312\/revisions"}],"predecessor-version":[{"id":20313,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20312\/revisions\/20313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/20311"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=20312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=20312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=20312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}