{"id":20195,"date":"2025-10-18T13:48:06","date_gmt":"2025-10-18T16:48:06","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=20195"},"modified":"2025-10-18T13:48:06","modified_gmt":"2025-10-18T16:48:06","slug":"jeannette-jara-encabeza-la-carrera-presidencial","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/10\/18\/jeannette-jara-encabeza-la-carrera-presidencial\/","title":{"rendered":"Jeannette Jara encabeza la carrera presidencial"},"content":{"rendered":"<p>Seg\u00fan la \u00faltima encuesta Panel Ciudadano UDD, Jeannette Jara se sit\u00faa en primer lugar de la carrera presidencial con el 24% de las preferencias. Jos\u00e9 Antonio Kast, del Partido Republicano, se ha desplazado al segundo puesto con un 23%, tras perder dos puntos. Evelyn Matthei, candidata de Chile Vamos, mantiene el tercer lugar con un 16%. Johannes Kaiser subi\u00f3 tres puntos y obtuvo el 13% de las preferencias.<\/p>\n<p>En caso de segunda vuelta, Jara no lograr\u00eda derrotar a Kast ni a Matthei. Con Kast como rival, Jara obtendr\u00eda el 33%, mientras que Kast sumar\u00eda un 46%. Si el segundo lugar lo ocupa Matthei, Jara se quedar\u00eda con el 30% frente al 45% de la candidata del partido oficialista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan la \u00faltima encuesta Panel Ciudadano UDD, Jeannette Jara se sit\u00faa en primer lugar de la carrera presidencial con el 24% de las preferencias. Jos\u00e9 Antonio Kast, del Partido Republicano, se ha desplazado al segundo puesto con un 23%, tras perder dos puntos. Evelyn Matthei, candidata de Chile Vamos, mantiene el tercer lugar con un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20194,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-20195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/10\/homepiaiextractoscrapimg_webplugarJaraJeannetteJaracarrera_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=20195"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20195\/revisions"}],"predecessor-version":[{"id":20196,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20195\/revisions\/20196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/20194"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=20195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=20195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=20195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}