{"id":20170,"date":"2025-10-17T08:38:43","date_gmt":"2025-10-17T11:38:43","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=20170"},"modified":"2025-10-17T08:38:43","modified_gmt":"2025-10-17T11:38:43","slug":"franja-electoral-inicia-en-este-viernes","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/10\/17\/franja-electoral-inicia-en-este-viernes\/","title":{"rendered":"Franja Electoral inicia en este Viernes"},"content":{"rendered":"<p>Este viernes 17 de octubre inicia la primera transmisi\u00f3n de la franja electoral en las Elecciones Presidenciales y Parlamentarias 2025. La franja se emite dos veces al d\u00eda, en un bloque de 20 minutos para los candidatos presidenciales y parlamentarios.<\/p>\n<p>Mientras que el espacio diurno, a las 12:40 horas, seguir\u00e1 las campa\u00f1as de los 8 aspirantes a La Moneda, el horario vespertino, fijado para las 20:40 horas, mostrar\u00e1 a los candidatos a diputados y senadores. Las tandas podr\u00e1n ser seguidas en televisi\u00f3n abierta como cadena nacional, es decir, que todos los canales transmitir\u00e1n la franja al mismo tiempo.<\/p>\n<p>En tanto, el Servicio Electoral de Chile (Servel) y el Consejo Nacional de Televisi\u00f3n (CNTV) sortearon el orden de aparici\u00f3n de los candidatos presidenciales y parlamentarios. Para la transmisi\u00f3n de las 12:40 horas del viernes, el orden ser\u00e1 Jeannette Jara, Harold Mayne-Nicholls, Marco Enr\u00edquez-Ominami, Franco Parisi, Eduardo Art\u00e9s, Johannes Kaiser, Evelyn Matthei y Jos\u00e9 Antonio Kast.<\/p>\n<p>Este orden rotar\u00e1 a diario de manera que quien abra la franja en un d\u00eda, cerrar\u00e1 al siguiente, y as\u00ed sucesivamente. Cada uno de ellos tendr\u00e1 un total de 2 minutos y 30 segundos para aparecer en pantalla.<\/p>\n<p>Respecto a la aparici\u00f3n de los pactos y partidos para la elecci\u00f3n parlamentaria, el orden sorteado qued\u00f3 as\u00ed: Movimiento Amarillos por Chile; Izquierda Ecologista Popular Animalista y Humanista; Partido Alianza Verde Popular; Partido de Trabajadores Revolucionarios; Verdes, Regionalista y Humanistas; Independientes fuera de pacto; Cambio por Chile; Popular; Partido de la Gente; Partido Ecologista Verde; Chile Grande y Unido; y, Unidad por Chile.<\/p>\n<p>Sobre los tiempos que tendr\u00e1n en pantalla, el CNTV indica que \u201cla ley establece que a cada partido pol\u00edtico se le asignar\u00e1 un tiempo proporcional a los votos obtenidos en la \u00faltima elecci\u00f3n de diputados\u201d. Aquellos que no hayan participado tendr\u00e1n el mismo tiempo que el partido con menor votaci\u00f3n, y tambi\u00e9n se aplica al conjunto de candidaturas independientes, cuyo tiempo se divide equitativamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este viernes 17 de octubre inicia la primera transmisi\u00f3n de la franja electoral en las Elecciones Presidenciales y Parlamentarias 2025. La franja se emite dos veces al d\u00eda, en un bloque de 20 minutos para los candidatos presidenciales y parlamentarios. Mientras que el espacio diurno, a las 12:40 horas, seguir\u00e1 las campa\u00f1as de los 8 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20169,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-20170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/10\/homepiaiextractoscrapimg_webpFranjaElectoral_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=20170"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20170\/revisions"}],"predecessor-version":[{"id":20171,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20170\/revisions\/20171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/20169"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=20170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=20170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=20170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}