{"id":20101,"date":"2025-10-14T20:35:38","date_gmt":"2025-10-14T23:35:38","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=20101"},"modified":"2025-10-14T20:35:38","modified_gmt":"2025-10-14T23:35:38","slug":"keylor-navas-apoya-a-rival-tras-error-en-cancha","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/10\/14\/keylor-navas-apoya-a-rival-tras-error-en-cancha\/","title":{"rendered":"Keylor Navas apoya a rival tras error en cancha."},"content":{"rendered":"<p>Keylor Navas, arquero hist\u00f3rico de Costa Rica y exjugador del Real Madrid y PSG, protagoniz\u00f3 un emotivo momento tras la goleada a Nicaragua en las Eliminatorias. El &#8216;Fantasma&#8217; visit\u00f3 la banca rival para apoyar al portero Miguel Rodr\u00edguez, quien cometi\u00f3 errores desastrosos durante el partido.<\/p>\n<p>El entrenador nicarag\u00fcense, Marco Antonio Figueroa, reconoci\u00f3 tras el encuentro que &#8220;hoy la responsabilidad de la derrota es de Miguel y m\u00eda por ponerlo. Lo asumo\u2026 fueron cuatro errores de Miguel, no uno&#8221;, destacando su compromiso en la situaci\u00f3n.<\/p>\n<p>Sin embargo, Navas tom\u00f3 una actitud distinta. Inmediatamente despu\u00e9s del partido, el experimentado guardameta acudi\u00f3 a la banca de Nicaragua para hablar con Rodr\u00edguez. En un video se puede ver a Keylor mirando fijamente al portero rival y asintiendo cabalmente.<\/p>\n<p>Finalmente, Navas le dio la mano a Rodr\u00edguez, quien cerr\u00f3 el episodio con un abrazo. &#8220;Keylor Navas apoyando al portero de Nicaragua Miguel Rodr\u00edguez. Actitud de leyenda&#8221;, resalt\u00f3 TD M\u00e1s, medio costarricense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Keylor Navas, arquero hist\u00f3rico de Costa Rica y exjugador del Real Madrid y PSG, protagoniz\u00f3 un emotivo momento tras la goleada a Nicaragua en las Eliminatorias. El &#8216;Fantasma&#8217; visit\u00f3 la banca rival para apoyar al portero Miguel Rodr\u00edguez, quien cometi\u00f3 errores desastrosos durante el partido. El entrenador nicarag\u00fcense, Marco Antonio Figueroa, reconoci\u00f3 tras el encuentro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20100,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-20101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/10\/homepiaiextractoscrapimg_webpKeylorNavas_1.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=20101"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20101\/revisions"}],"predecessor-version":[{"id":20102,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/20101\/revisions\/20102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/20100"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=20101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=20101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=20101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}