{"id":19930,"date":"2025-10-08T07:47:06","date_gmt":"2025-10-08T10:47:06","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=19930"},"modified":"2025-10-08T07:47:06","modified_gmt":"2025-10-08T10:47:06","slug":"johnny-herrera-critica-al-cuerpo-tecnico-de-la-roja-sub-20-tras-eliminacion-del-mundial","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/10\/08\/johnny-herrera-critica-al-cuerpo-tecnico-de-la-roja-sub-20-tras-eliminacion-del-mundial\/","title":{"rendered":"Johnny Herrera critica al cuerpo t\u00e9cnico de La Roja Sub 20 tras eliminaci\u00f3n del Mundial."},"content":{"rendered":"<p>La Roja Sub 20 fue eliminada en octavos de final del Mundial ante M\u00e9xico, sufriendo una goleada por 1-4 en Valpara\u00edso. Esta dolorosa derrota gener\u00f3 mucha frustraci\u00f3n y cr\u00edticas, especialmente hacia el cuerpo t\u00e9cnico dirigido por Nicol\u00e1s C\u00f3rdova. Johnny Herrera, ex arquero y actual comentarista de TNT Sports, fue directo con sus opiniones, se\u00f1alando que las cr\u00edticas deben caer sobre los t\u00e9cnicos. <\/p>\n<p>Enfatiz\u00f3: &#8220;Ya dijimos cuando le pasaron la adulta (a C\u00f3rdova): compadre, el que mucho abarca, poco aprieta&#8221;. Herrera argument\u00f3 que los problemas del equipo no fueron producto de un desempe\u00f1o individual deficiente, sino de una falta de forma y juego colectivo. Para \u00e9l, esto es responsabilidad del cuerpo t\u00e9cnico.<\/p>\n<p>A pesar de reconocer el nivel de M\u00e9xico, Herrera defendi\u00f3 el talento chileno. Insinu\u00f3 que hubo decisiones incomprensibles desde el banco que afectaron la participaci\u00f3n de jugadores con condiciones, como Marchant y Godoy. <\/p>\n<p>Destac\u00f3 especialmente el potencial mostrado por Godoy en los pocos minutos que tuvo en cancha. Asever\u00f3: &#8220;Godoy demostr\u00f3 en cinco minutos que pudo encarar y pasarse a un jugador&#8221;. Tambi\u00e9n cuestion\u00f3 la falta de participaci\u00f3n de Marchant, conocido para todos.<\/p>\n<p>Finalmente, Herrera lament\u00f3 la falta de soltura del equipo chileno. Aunque reconoci\u00f3 el trabajo realizado por M\u00e9xico, insisti\u00f3 en que Chile ten\u00eda capital humano suficiente para competir. Concluy\u00f3: &#8220;Cuando el equipo se solt\u00f3 un poquito, hizo da\u00f1o&#8221;, mostrando pesar por la actuaci\u00f3n fallida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Roja Sub 20 fue eliminada en octavos de final del Mundial ante M\u00e9xico, sufriendo una goleada por 1-4 en Valpara\u00edso. Esta dolorosa derrota gener\u00f3 mucha frustraci\u00f3n y cr\u00edticas, especialmente hacia el cuerpo t\u00e9cnico dirigido por Nicol\u00e1s C\u00f3rdova. Johnny Herrera, ex arquero y actual comentarista de TNT Sports, fue directo con sus opiniones, se\u00f1alando que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19929,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-19930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/10\/homepiaiextractoscrapimg_predeterminadalaserenaradio_deportes-4.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=19930"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19930\/revisions"}],"predecessor-version":[{"id":19931,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19930\/revisions\/19931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/19929"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=19930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=19930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=19930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}