{"id":19870,"date":"2025-10-06T14:44:41","date_gmt":"2025-10-06T17:44:41","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=19870"},"modified":"2025-10-06T14:44:41","modified_gmt":"2025-10-06T17:44:41","slug":"la-candidata-jeannette-jara-enfrenta-criticas-por-programa-economico-y-conflicto-con-ministro-de-vivienda","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/10\/06\/la-candidata-jeannette-jara-enfrenta-criticas-por-programa-economico-y-conflicto-con-ministro-de-vivienda\/","title":{"rendered":"La candidata Jeannette Jara enfrenta cr\u00edticas por programa econ\u00f3mico y conflicto con ministro de Vivienda"},"content":{"rendered":"<p>Los partidos oficialistas respaldaron el anexo program\u00e1tico de gobierno presentado por Jeannette Jara (PC), enfatizando pilares como el salario vital de $750 mil y la restricci\u00f3n del uso de la Unidad de Fomento (UF). Aunque la Democracia Cristiana (DC) mostr\u00f3 desmarques, estos temas forman parte central del documento.<\/p>\n<p>Respecto a la inclusi\u00f3n del aborto legal en su programa, Jara argument\u00f3 que el anexo refleja una buena se\u00f1al de gobernabilidad al agrupar la mayor parte de la centro izquierda en torno a una propuesta com\u00fan. <\/p>\n<p>Camila Mirando, vocera del comando, explic\u00f3 que el salario vital es un paso gradual y responsable, dise\u00f1ado para asegurar un ingreso real que cubra los costos de vida sin comprometer la creaci\u00f3n de empleo.<\/p>\n<p>Mientras tanto, una tensi\u00f3n adicional surgi\u00f3 entre Jara y Carlos Montes, ministro de Vivienda y Urbanismo. Este \u00faltimo acus\u00f3 a un asesor del comando de la candidata con el due\u00f1o de una megatoma en San Antonio. En respuesta, Montes rechaz\u00f3 las acusaciones, afirmando que solo mencion\u00f3 diferentes formas de di\u00e1logo.<\/p>\n<p>Jara desminti\u00f3 estas acusaciones y pidi\u00f3 al ministro explicaciones e intervenci\u00f3n en la situaci\u00f3n. Asegur\u00f3 desconocimiento sobre los comentarios y lament\u00f3 que se generen debates sin fundamento a ra\u00edz de cr\u00edticas a la reconstrucci\u00f3n en Vi\u00f1a del Mar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los partidos oficialistas respaldaron el anexo program\u00e1tico de gobierno presentado por Jeannette Jara (PC), enfatizando pilares como el salario vital de $750 mil y la restricci\u00f3n del uso de la Unidad de Fomento (UF). Aunque la Democracia Cristiana (DC) mostr\u00f3 desmarques, estos temas forman parte central del documento. Respecto a la inclusi\u00f3n del aborto legal [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19869,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-19870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/10\/homepiaiextractoscrapimg_webpJaraministroanexoJeannetteJara_1.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=19870"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19870\/revisions"}],"predecessor-version":[{"id":19871,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19870\/revisions\/19871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/19869"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=19870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=19870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=19870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}