{"id":19381,"date":"2025-09-08T09:51:31","date_gmt":"2025-09-08T12:51:31","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=19381"},"modified":"2025-09-08T09:51:31","modified_gmt":"2025-09-08T12:51:31","slug":"desvalijan-casa-de-diputado-palma","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/09\/08\/desvalijan-casa-de-diputado-palma\/","title":{"rendered":"Desvalijan casa de diputado Palma"},"content":{"rendered":"<p>El diputado Hern\u00e1n Palma denunci\u00f3 este domingo que desvalijaron su casa mientras estaba fuera. En su cuenta de X, describi\u00f3 c\u00f3mo se llevaron el auto de su pareja y varios electrodom\u00e9sticos.<\/p>\n<p>Palma, residente en Pe\u00f1alol\u00e9n, no es la primera vez que experimenta este tipo de incidentes. Durante este semestre, su oficina distrital fue vandalizada cinco veces, siendo la \u00faltima durante esta misma semana.<\/p>\n<p>\u00a1Basta de impunidad! Finaliz\u00f3 el diputado por el 12\u00b0 Distrito y Regi\u00f3n Metropolitana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El diputado Hern\u00e1n Palma denunci\u00f3 este domingo que desvalijaron su casa mientras estaba fuera. En su cuenta de X, describi\u00f3 c\u00f3mo se llevaron el auto de su pareja y varios electrodom\u00e9sticos. Palma, residente en Pe\u00f1alol\u00e9n, no es la primera vez que experimenta este tipo de incidentes. Durante este semestre, su oficina distrital fue vandalizada cinco [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19380,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-19381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/09\/homepiaiextractoscrapimg_predeterminadalaserenaradio_politica-2.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=19381"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19381\/revisions"}],"predecessor-version":[{"id":19382,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19381\/revisions\/19382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/19380"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=19381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=19381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=19381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}