{"id":19237,"date":"2025-09-01T15:54:56","date_gmt":"2025-09-01T18:54:56","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=19237"},"modified":"2025-09-01T15:54:56","modified_gmt":"2025-09-01T18:54:56","slug":"carlos-caszely-propone-a-el-fantasma-figueroa-como-entrenador-chileno","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/09\/01\/carlos-caszely-propone-a-el-fantasma-figueroa-como-entrenador-chileno\/","title":{"rendered":"Carlos Caszely propone a &#8220;El Fantasma&#8221; Figueroa como entrenador chileno."},"content":{"rendered":"<p>Carlos Caszely, hist\u00f3rico delantero de La Roja, sorprendi\u00f3 con su candidato a la banca de la Selecci\u00f3n chilena. De cara a la \u00faltima doble fecha de Eliminatorias, donde el eliminado combinado nacional enfrentar\u00e1 a Brasil y Uruguay con Nicol\u00e1s C\u00f3rdova en la banca, el exjugador se la jug\u00f3 con el nombre de un entrenador chileno.<\/p>\n<p>&#8220;Hay uno que lo odia todo el mundo, pero yo creo que le har\u00eda muy bien, porque tiene una personalidad enormemente grande: el \u2018Fantasma\u2019 Figueroa&#8221;, dijo Caszely en M\u00e1ximas de TNT Sports. Todo el mundo lo odia, pero lo odian porque es directo, y en este pa\u00eds ser directo es un poco complicado. Creo que el tipo pondr\u00eda las reglas claras. En Cat\u00f3lica le fue bien.<\/p>\n<p>Vale recordar que Chile visitar\u00e1 a Brasil este jueves 4 de septiembre, a partir de las 20:30 horas. Luego, La Roja recibir\u00e1 a Uruguay el martes 9 -desde las 20:30 horas- para cerrar las Eliminatorias al Mundial 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carlos Caszely, hist\u00f3rico delantero de La Roja, sorprendi\u00f3 con su candidato a la banca de la Selecci\u00f3n chilena. De cara a la \u00faltima doble fecha de Eliminatorias, donde el eliminado combinado nacional enfrentar\u00e1 a Brasil y Uruguay con Nicol\u00e1s C\u00f3rdova en la banca, el exjugador se la jug\u00f3 con el nombre de un entrenador chileno. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19236,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-19237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/09\/homepiaiextractoscrapimg_predeterminadalaserenaradio_deportes.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=19237"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19237\/revisions"}],"predecessor-version":[{"id":19238,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19237\/revisions\/19238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/19236"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=19237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=19237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=19237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}