{"id":19192,"date":"2025-08-30T17:04:13","date_gmt":"2025-08-30T20:04:13","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=19192"},"modified":"2025-08-30T17:04:13","modified_gmt":"2025-08-30T20:04:13","slug":"magdalena-pinera-se-reune-con-evelyn-matthei","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/08\/30\/magdalena-pinera-se-reune-con-evelyn-matthei\/","title":{"rendered":"Magdalena Pi\u00f1era se re\u00fane con Evelyn Matthei"},"content":{"rendered":"<p>Magdalena Pi\u00f1era Morel, hija del expresidente Sebasti\u00e1n Pi\u00f1era, agend\u00f3 un encuentro para este lunes con Evelyn Matthei y excolaboradores de su padre. El objetivo es reforzar el v\u00ednculo con la candidata y evitar una fuga de votos.<\/p>\n<p>Esta decisi\u00f3n se produce en medio de desmarques dentro del Chile Vamos, donde figuras importantes como Jorge Atton, \u00c1lvaro Cruzat, Ricardo Irarr\u00e1zabal y Rodrigo \u00c1lvarez expresaron p\u00fablicamente su apoyo a Jos\u00e9 Antonio Kast.<\/p>\n<p>Desde Dem\u00f3cratas, la senadora Ximena Rinc\u00f3n afirm\u00f3 que este encuentro reafirma el involucramiento de la familia Pi\u00f1era Morel en la campa\u00f1a de Matthei. Record\u00f3 que no solo han respaldado p\u00fablicamente a Evelyn Matthei, sino que tambi\u00e9n han donado $24 millones a su campa\u00f1a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Magdalena Pi\u00f1era Morel, hija del expresidente Sebasti\u00e1n Pi\u00f1era, agend\u00f3 un encuentro para este lunes con Evelyn Matthei y excolaboradores de su padre. El objetivo es reforzar el v\u00ednculo con la candidata y evitar una fuga de votos. Esta decisi\u00f3n se produce en medio de desmarques dentro del Chile Vamos, donde figuras importantes como Jorge Atton, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19191,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-19192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/08\/homepiaiextractoscrapimg_webpEvelynMattheiMagdalenaMorelencuentro_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=19192"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19192\/revisions"}],"predecessor-version":[{"id":19193,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/19192\/revisions\/19193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/19191"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=19192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=19192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=19192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}