{"id":18976,"date":"2025-08-21T10:37:20","date_gmt":"2025-08-21T13:37:20","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=18976"},"modified":"2025-08-21T10:37:20","modified_gmt":"2025-08-21T13:37:20","slug":"el-presidente-boric-envia-a-un-ministro-a-argentina-para-proteger-a-hinchas-chilenos-heridos","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/08\/21\/el-presidente-boric-envia-a-un-ministro-a-argentina-para-proteger-a-hinchas-chilenos-heridos\/","title":{"rendered":"El presidente Boric env\u00eda a un ministro a Argentina para proteger a hinchas chilenos heridos"},"content":{"rendered":"<p>El Presidente Gabriel Boric inform\u00f3 la ma\u00f1ana de este jueves que el ministro \u00c1lvaro Elizalde viajar\u00e1 a Buenos Aires para supervisar la situaci\u00f3n de hinchas chilenos heridos en incidentes ocurridos tras un partido entre Independiente y Universidad de Chile.<\/p>\n<p>A trav\u00e9s de su cuenta de X, Boric resalt\u00f3 lo inaceptable del linchamiento de chilenos en el estadio de Independiente. El mandatario instruy\u00f3 al Ministro del Interior para que viaje a Buenos Aires con el Embajador, acompa\u00f1ando personalmente a los heridos y revisando la situaci\u00f3n de los detenidos.<\/p>\n<p>Boric enfatiz\u00f3: &#8220;La violencia no tiene justificaci\u00f3n alguna y protegeremos los derechos de nuestros ciudadanos sin perjuicio de las responsabilidades judiciales&#8221;.<\/p>\n<p>Seg\u00fan el embajador Jos\u00e9 Antonio Viera-Gallo, m\u00e1s de 100 hinchas de la &#8220;U&#8221; han sido detenidos. El diplom\u00e1tico indic\u00f3 que probablemente podr\u00edan salir ma\u00f1ana tras un an\u00e1lisis de participaci\u00f3n en hechos delictuales.<\/p>\n<p>Viera-Gallo a\u00f1adi\u00f3: &#8220;Las condiciones de la comisar\u00eda no son \u00f3ptimas, pero los detenidos no est\u00e1n siendo maltratados&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Presidente Gabriel Boric inform\u00f3 la ma\u00f1ana de este jueves que el ministro \u00c1lvaro Elizalde viajar\u00e1 a Buenos Aires para supervisar la situaci\u00f3n de hinchas chilenos heridos en incidentes ocurridos tras un partido entre Independiente y Universidad de Chile. A trav\u00e9s de su cuenta de X, Boric resalt\u00f3 lo inaceptable del linchamiento de chilenos en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18975,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-18976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/08\/homepiaiextractoscrapimg_webpBoricArgentina_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=18976"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18976\/revisions"}],"predecessor-version":[{"id":18977,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18976\/revisions\/18977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/18975"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=18976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=18976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=18976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}