{"id":18916,"date":"2025-08-19T19:46:04","date_gmt":"2025-08-19T22:46:04","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=18916"},"modified":"2025-08-19T19:46:04","modified_gmt":"2025-08-19T22:46:04","slug":"la-camara-de-diputadas-y-diputados-aprueba-proyecto-de-pruebas-de-drogas-obligatorias-para-funcionarios-y-candidatos","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/08\/19\/la-camara-de-diputadas-y-diputados-aprueba-proyecto-de-pruebas-de-drogas-obligatorias-para-funcionarios-y-candidatos\/","title":{"rendered":"La C\u00e1mara de Diputadas y Diputados aprueba proyecto de pruebas de drogas obligatorias para funcionarios y candidatos."},"content":{"rendered":"<p>La C\u00e1mara de Diputadas y Diputados aprob\u00f3 con 115 votos a favor y 17 abstenciones la iniciativa que establece test de drogas obligatorios para autoridades y candidatos en todas las reparticiones del Estado. El proyecto busca que parlamentarios, ministros, subsecretarios, gobernadores regionales, alcaldes e incluso el Presidente de la Rep\u00fablica realicen un test al menos una vez al a\u00f1o durante el ejercicio de sus cargos. <\/p>\n<p>El test se realizar\u00eda por un laboratorio autorizado del <a href=\"http:\/\/www.minsal.cl\/\">Ministerio de Salud<\/a>, conforme a est\u00e1ndares internacionales y basado en una muestra de cabello. Tras meses de discusi\u00f3n y dilaci\u00f3n, la iniciativa ir\u00e1 al Senado despu\u00e9s de pasar por un segundo informe de la Comisi\u00f3n de Gobierno Interior que ya hab\u00eda realizado cuestionamientos a su contenido.<\/p>\n<p>En la votaci\u00f3n, si bien nadie estuvo en contra, las abstenciones correspondieron principalmente a parlamentarios del Frente Amplio y el Partido Comunista. Antes de la votaci\u00f3n, el diputado de la UDI, Juan Antonio Coloma, acus\u00f3 que el proyecto se vot\u00f3 hoy, y no antes, porque existe un punto en que se obliga a quienes se inscriben como candidatos a presentar una declaraci\u00f3n jurada de que no consumen drogas. &#8220;No es casualidad que el Gobierno hiciera todo lo posible por demorar este proyecto&#8221;, acus\u00f3.<\/p>\n<p>Desde el oficialismo accedieron a apoyar la iniciativa, pero recalcaron en que no resolver\u00e1 el problema de fondo: el narcotr\u00e1fico. En esa l\u00ednea, el diputado Diego Ib\u00e1\u00f1ez (FA) apunt\u00f3: &#8220;Si le hubi\u00e9semos hecho un test de drogas a Pablo Escobar sale negativo. (&#8230;) Vamos a apoyar el proyecto, estamos de acuerdo, pero no argumentemos que esto va a terminar con el narcotr\u00e1fico, porque eso es rid\u00edculo&#8221;.<\/p>\n<p>Por su parte, el diputado de Ev\u00f3poli, Francisco Undurraga, al igual que algunos de sus pares de centro-derecha, plante\u00f3 que puede que no sea una gran soluci\u00f3n, pero es un gesto necesario para darle garant\u00eda de transparencia a la ciudadan\u00eda. &#8220;Al menos le da una tranquilidad a los ciudadanos que quienes estamos en posiciones de poder no tenemos relaciones con la droga&#8221;, afirm\u00f3.<\/p>\n<p>Pese a la votaci\u00f3n, la discusi\u00f3n por detectar v\u00ednculos con el narco contin\u00faa. Esto porque el oficialismo insiste en el levantamiento bancario por v\u00eda administrativa, argumentando que la facultad que actualmente tiene la Justicia es muy engorrosa. &#8220;Este congreso tiene la obligaci\u00f3n de levantar todas las barreras para impedir que su influencia (del narco) se instale en el coraz\u00f3n del Estado&#8221;, postul\u00f3 el diputado Marcos Ilabaca (PS).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La C\u00e1mara de Diputadas y Diputados aprob\u00f3 con 115 votos a favor y 17 abstenciones la iniciativa que establece test de drogas obligatorios para autoridades y candidatos en todas las reparticiones del Estado. El proyecto busca que parlamentarios, ministros, subsecretarios, gobernadores regionales, alcaldes e incluso el Presidente de la Rep\u00fablica realicen un test al menos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18915,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-18916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/08\/homepiaiextractoscrapimg_webpproyectotestdrogasdiputado_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=18916"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18916\/revisions"}],"predecessor-version":[{"id":18917,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18916\/revisions\/18917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/18915"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=18916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=18916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=18916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}