{"id":18874,"date":"2025-08-18T22:05:12","date_gmt":"2025-08-19T01:05:12","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=18874"},"modified":"2025-08-18T22:05:12","modified_gmt":"2025-08-19T01:05:12","slug":"dos-candidatos-presidenciales-se-inscriben-ante-servel","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/08\/18\/dos-candidatos-presidenciales-se-inscriben-ante-servel\/","title":{"rendered":"Dos candidatos presidenciales se inscriben ante Servel"},"content":{"rendered":"<p>Harold Mayne-Nicholls y Eduardo Art\u00e9s inscribieron sus candidaturas presidenciales ante el Servicio Electoral (Servel) en Santiago, marcando el inicio oficial de sus campa\u00f1as para la elecci\u00f3n de noviembre.<\/p>\n<p>Mayne-Nicholls, quien lleg\u00f3 primero al organismo electoral, expres\u00f3 altas expectativas para la contienda y se comprometi\u00f3 a presentar su programa de gobierno durante esta semana. En una declaraci\u00f3n p\u00fablica, Mayne-Nicholls esboz\u00f3 los lineamientos centrales que guiar\u00e1n su eventual gesti\u00f3n: &#8220;En primer lugar, es la seguridad como un todo, seguridad p\u00fablica y seguridad ciudadana, pero tambi\u00e9n seguridad en salud, en educaci\u00f3n, en vivienda, en jur\u00eddica, seguridad para los inversionistas&#8221;, destac\u00f3.<\/p>\n<p>El candidato independiente enfatiz\u00f3 que su propuesta se sostiene sobre cuatro pilares fundamentales: educaci\u00f3n, desatar el crecimiento econ\u00f3mico, salud y vivienda. Mayne-Nicholls expres\u00f3 confianza en superar la primera vuelta, basando este optimismo en la extensa recolecci\u00f3n de firmas realizada. &#8220;Nosotros en la b\u00fasqueda de firmas recorrimos 85 comunas del pa\u00eds. Hoy d\u00eda hicimos la presentaci\u00f3n, la cantidad de kil\u00f3metros que hicimos era, si no me equivoco, 5,3 veces desde Visviri hasta la Ant\u00e1rtida y de vuelta&#8221;, se\u00f1al\u00f3. A\u00f1adi\u00f3 que continuar\u00e1n visitando comunas para convencer a la ciudadan\u00eda.<\/p>\n<p>Respecto de sus expectativas de campa\u00f1a, Mayne-Nicholls hizo un llamado a una contienda limpia y centrada en las propuestas: &#8220;Yo espero que sea una lucha limpia, una lucha donde se impongan las ideas y no los temas personales, que no haya agresiones, que se acaben todas estas cosas que hemos escuchado en los \u00faltimos d\u00edas&#8221;, se\u00f1al\u00f3. A\u00f1adi\u00f3 que esas situaciones le incomodan y perjudican al pa\u00eds y la pol\u00edtica, aspirando a una elecci\u00f3n que genere orgullo.<\/p>\n<p>Pasadas las 19:00 horas, Eduardo Art\u00e9s lleg\u00f3 al Servel para inscribir su tercera candidatura presidencial. El profesor plante\u00f3 una cr\u00edtica radical al sistema imperante, argumentando que &#8220;nuestra candidatura se inscribe en la necesidad de cambiar el modelo econ\u00f3mico y social existente. No es una candidatura cosm\u00e9tica para cambiar algunas cositas y seguir en m\u00e1s de lo mismo, como han sido todos los gobiernos que hemos tenido desde la salida del dictador de La Moneda&#8221;.<\/p>\n<p>Art\u00e9s atribuy\u00f3 su postulaci\u00f3n a un profundo descontento social: &#8220;Es impulsada por un descontento muy fuerte, grande, con un racismo falso, de una izquierda indefinida, hidrop\u00f3nica, que no est\u00e1 por las transformaciones que reclama la sociedad&#8221;, afirm\u00f3. En esa l\u00ednea, defini\u00f3 su proyecto como un &#8220;gobierno patri\u00f3tico, popular, de perspectiva socialista&#8221;, enfatizando que su programa busca transformar la sociedad.<\/p>\n<p>Consultado sobre un posible apoyo a Jeannette Jara, candidata de la centro-izquierda, en una segunda vuelta donde \u00e9l no estuviera presente, Art\u00e9s condicion\u00f3 su respaldo: &#8220;Con el programa actual que est\u00e1 confeccionando Jeannette Jara, yo no votar\u00eda por ella&#8221;, expres\u00f3. As\u00ed las cosas, el candidato estableci\u00f3 requisitos espec\u00edficos para un eventual apoyo: &#8220;Tendr\u00eda que aceptar algunos puntos de nuestro programa, fundamentalmente en renacionalizaci\u00f3n de los recursos naturales o recuperaci\u00f3n del cobre, el litio, etc. Si estamos de acuerdo en algunas cosas de ese tipo, quiz\u00e1s podemos conversar&#8221;, cerr\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Harold Mayne-Nicholls y Eduardo Art\u00e9s inscribieron sus candidaturas presidenciales ante el Servicio Electoral (Servel) en Santiago, marcando el inicio oficial de sus campa\u00f1as para la elecci\u00f3n de noviembre. Mayne-Nicholls, quien lleg\u00f3 primero al organismo electoral, expres\u00f3 altas expectativas para la contienda y se comprometi\u00f3 a presentar su programa de gobierno durante esta semana. En una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18873,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-18874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/08\/homepiaiextractoscrapimg_webpServelNicholls_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=18874"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18874\/revisions"}],"predecessor-version":[{"id":18875,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18874\/revisions\/18875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/18873"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=18874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=18874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=18874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}