{"id":18629,"date":"2025-08-09T23:46:11","date_gmt":"2025-08-10T02:46:11","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=18629"},"modified":"2025-08-09T23:46:11","modified_gmt":"2025-08-10T02:46:11","slug":"desbordes-reconocio-ante-causa-contra-hassler","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/08\/09\/desbordes-reconocio-ante-causa-contra-hassler\/","title":{"rendered":"Desbordes reconoci\u00f3 ante causa contra Hassler"},"content":{"rendered":"<p>El abogado defensor de Irac\u00ed Hassler, Miguel Sch\u00fcrmann, respondi\u00f3 las acusaciones del alcalde de Santiago, Mario Desbordes, sobre su declaraci\u00f3n como imputado en el caso de conversaciones ilegales. Sch\u00fcrmann aleg\u00f3 que Desbordes afirm\u00f3 no saber si Hassler es &#8220;mentirosa patol\u00f3gica&#8221; o si sus declaraciones tienen que ver con una campa\u00f1a pol\u00edtica.<\/p>\n<p>Sch\u00fcrmann mencion\u00f3 un documento al que accedi\u00f3 BioBioChile, que evidencia que efectivamente Desbordes declar\u00f3 como imputado en el caso de filtraci\u00f3n. Seg\u00fan Sch\u00fcrmann: &#8220;Es derechamente falso lo que \u00e9l afirma&#8221;. Adem\u00e1s, agreg\u00f3 que si el alcalde ha sufrido alguna forma de amnesia o bloqueo durante la declaraci\u00f3n, debe preguntar a su propio abogado defensor y solicitar los antecedentes.<\/p>\n<p>El documento muestra que Desbordes concurri\u00f3 personalmente ante el Fiscal adjunto Claudio Rebeco el 1 de julio en compa\u00f1\u00eda de su defensor Sergio Contreras Paredes. Esto confirma la imputaci\u00f3n en la causa de filtraciones ilegales, se\u00f1al\u00f3 Sch\u00fcrmann.<\/p>\n<p>Por otro lado, Desbordes neg\u00f3 haber filtrado informaci\u00f3n e acus\u00f3 a Hassler de intentar desviar la atenci\u00f3n para evitar responder por un delito de tr\u00e1fico de influencias. El alcalde afirm\u00f3 que el municipio continuar\u00e1 las acciones judiciales en el caso Sierra Bella, pese a la revocaci\u00f3n por la Quinta Sala de la Corte de Apelaciones de Santiago.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El abogado defensor de Irac\u00ed Hassler, Miguel Sch\u00fcrmann, respondi\u00f3 las acusaciones del alcalde de Santiago, Mario Desbordes, sobre su declaraci\u00f3n como imputado en el caso de conversaciones ilegales. Sch\u00fcrmann aleg\u00f3 que Desbordes afirm\u00f3 no saber si Hassler es &#8220;mentirosa patol\u00f3gica&#8221; o si sus declaraciones tienen que ver con una campa\u00f1a pol\u00edtica. Sch\u00fcrmann mencion\u00f3 un documento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18628,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-18629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/08\/homepiaiextractoscrapimg_webpDesbordesHasslerdefensoralcalde_1.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=18629"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18629\/revisions"}],"predecessor-version":[{"id":18630,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18629\/revisions\/18630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/18628"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=18629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=18629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=18629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}