{"id":18584,"date":"2025-08-07T10:42:17","date_gmt":"2025-08-07T13:42:17","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=18584"},"modified":"2025-08-07T10:42:17","modified_gmt":"2025-08-07T13:42:17","slug":"diferencias-entre-jeannette-jara-y-su-equipo-economico","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/08\/07\/diferencias-entre-jeannette-jara-y-su-equipo-economico\/","title":{"rendered":"Diferencias entre Jeannette Jara y su equipo econ\u00f3mico."},"content":{"rendered":"<p>Importantes diferencias se generaron entre la candidata del pacto Unidad por Chile, Jeannette Jara, y sus nuevos asesores en materia econ\u00f3mica. En relaci\u00f3n a los datos de desempleo, su asesor econ\u00f3mico, Luis Eduardo Escobar, reconoci\u00f3 que las recientes cifras \u201cson un desastre\u201d. Por otro lado, Osvaldo Rosales, miembro del equipo de Jara, descart\u00f3 terminar con las AFP, como lo hab\u00eda planteado la candidata durante la campa\u00f1a.<\/p>\n<p>En un seminario junto a otros jefes econ\u00f3micos de campa\u00f1a, Escobar afirm\u00f3 que \u201choy tenemos 25 ministerios y algunos pa\u00edses, los m\u00e1s poderosos, 9 o 12; \u00bfc\u00f3mo un Presidente va a dirigir una reuni\u00f3n de gabinete? \u00bfC\u00f3mo se van a poner de acuerdo 26 personas? El sistema est\u00e1 fallido\u201d. No obstante, Escobar precis\u00f3 que es un tema que no ha hablado con la candidata.<\/p>\n<p>Rosales indic\u00f3 en CNN Chile Radio que \u201cse aprob\u00f3 una reforma de pensiones y hay que jugarse para que esa reforma se aplique. Por tanto, el tema de cambio de las AFP no est\u00e1 en la agenda econ\u00f3mica ad portas\u201d. Jara fue consultada sobre estas dos dimensiones.<\/p>\n<p>Sobre disminuir ministerios, la candidata evit\u00f3 entrar al choque y dijo que \u201ctodas las conversaciones program\u00e1ticas las estamos dando, no me voy a cerrar a debates, pero en modernizaci\u00f3n del Estado a m\u00ed me interesa que el Estado se fortalezca, donde no hay Estado entra el crimen organizado, el Estado tiene desaf\u00edos de modernizaci\u00f3n y esa conversaci\u00f3n la vamos a hacer con los funcionarios\u201d, enfatiz\u00f3.<\/p>\n<p>Frente a las calificaciones de Escobar sobre las cifras laborales como \u201cdesastrosas\u201d, Jara prefiri\u00f3 apuntar a las eventuales causas, se\u00f1alando que \u201cen materia de empleo el debate que debemos dar es c\u00f3mo preparamos nuestro mercado laboral para los cambios que se est\u00e1n experimentando. Pareciera que no est\u00e1 pasando nada, cuando la IA, la automatizaci\u00f3n y la multifuncionalidad le han pegado duro al empleo\u201d.<\/p>\n<p>Defendi\u00f3 su gesti\u00f3n al mando del Ministerio del Trabajo, se\u00f1alando que \u201ccuando fui ministra tuvimos la posibilidad de crear 570 mil empleos, no 141 como dice Evelyn Matthei, que lo encuentro realmente muy lamentable. Pero si damos el debate en base a peque\u00f1as consignas, no vamos a solucionar el futuro del empleo\u201d.<\/p>\n<p>En relaci\u00f3n al fin de las AFP, Jara mantuvo su visi\u00f3n con menos ambig\u00fcedad: \u201cSi las AFP se pueden terminar o no, va a depender mucho de la correlaci\u00f3n de fuerzas pol\u00edtica y social que tengamos. Yo en eso he sido clara, a m\u00ed me hubiera gustado que en este Gobierno se hubieran terminado las AFP, pero no se pudo, porque aunque a la gente las AFP no le gustan, escogi\u00f3 a muchos parlamentarios a los que s\u00ed le gustan, y las defendieron en el Parlamento con dientes y u\u00f1as\u201d, enfatiz\u00f3.<\/p>\n<p>As\u00ed, la exministra intenta zanjar las diferencias con su actual equipo program\u00e1tico, se\u00f1alando que \u201cpara terminar con las AFP hay varios caminos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Importantes diferencias se generaron entre la candidata del pacto Unidad por Chile, Jeannette Jara, y sus nuevos asesores en materia econ\u00f3mica. En relaci\u00f3n a los datos de desempleo, su asesor econ\u00f3mico, Luis Eduardo Escobar, reconoci\u00f3 que las recientes cifras \u201cson un desastre\u201d. Por otro lado, Osvaldo Rosales, miembro del equipo de Jara, descart\u00f3 terminar con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18583,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-18584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/08\/homepiaiextractoscrapimg_webpcandidataJaraEstadoequipo_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=18584"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18584\/revisions"}],"predecessor-version":[{"id":18585,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18584\/revisions\/18585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/18583"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=18584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=18584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=18584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}