{"id":18563,"date":"2025-08-06T19:31:55","date_gmt":"2025-08-06T22:31:55","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=18563"},"modified":"2025-08-06T19:31:55","modified_gmt":"2025-08-06T22:31:55","slug":"senador-rn-apoyara-a-jose-antonio-kast-frente-a-evelyn-matthei","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/08\/06\/senador-rn-apoyara-a-jose-antonio-kast-frente-a-evelyn-matthei\/","title":{"rendered":"Senador RN apoyar\u00e1 a Jos\u00e9 Antonio Kast frente a Evelyn Matthei"},"content":{"rendered":"<p>Evelyn Matthei, candidata presidencial de Chile Vamos, sufre un nuevo contratiempo en su campa\u00f1a al perder el apoyo del senador Alejandro Kusanovic (RN), quien decidi\u00f3 votar por Jos\u00e9 Antonio Kast, abanderado del Partido Republicano.<\/p>\n<p>Kusanovic declar\u00f3 a Diario La Segunda que Matthei debi\u00f3 haber representado sus propias ideas y no estar influenciada por un grupo proveniente del gobierno de Pi\u00f1era. El senador agreg\u00f3 que ella deber\u00eda haber aparecido como algo nuevo, reconociendo los errores pasados para tener un resultado exitoso.<\/p>\n<p>En el mismo di\u00e1logo, Kusanovic critic\u00f3 a Juan Sutil y al senador Juan Antonio Coloma, quienes seg\u00fan \u00e9l, representan \u201clo mismo\u201d y podr\u00edan socavar las aspiraciones de Matthei. El legislador argument\u00f3 que la gente busca algo nuevo, lo cual estos pol\u00edticos tradicionales no ofrecen.<\/p>\n<p>No obstante, Kusanovic explic\u00f3 que aunque Matthei es la candidata de su partido, votar\u00e1 por el candidato de derecha que est\u00e9 en mejor posici\u00f3n para ganar, en este caso, Jos\u00e9 Antonio Kast. Considera que Kast tiene el car\u00e1cter necesario para enfrentar los problemas y sintonizar correctamente con las expectativas del p\u00fablico.<\/p>\n<p>Finalmente, Kusanovic fue claro sobre su postura, indicando que no teme ser expulsado de RN por sus declaraciones, ya que siempre ha sido independiente en la expresi\u00f3n de su pensamiento. Afirma que la libertad es fundamental para el crecimiento de un pa\u00eds y que si debe renunciar al partido, lo har\u00e1 sin miedo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evelyn Matthei, candidata presidencial de Chile Vamos, sufre un nuevo contratiempo en su campa\u00f1a al perder el apoyo del senador Alejandro Kusanovic (RN), quien decidi\u00f3 votar por Jos\u00e9 Antonio Kast, abanderado del Partido Republicano. Kusanovic declar\u00f3 a Diario La Segunda que Matthei debi\u00f3 haber representado sus propias ideas y no estar influenciada por un grupo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18562,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-18563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/08\/homepiaiextractoscrapimg_webpKusanovicnuevosenadorAntonioKast_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=18563"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18563\/revisions"}],"predecessor-version":[{"id":18564,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18563\/revisions\/18564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/18562"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=18563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=18563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=18563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}