{"id":18515,"date":"2025-08-05T12:55:15","date_gmt":"2025-08-05T15:55:15","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=18515"},"modified":"2025-08-05T12:55:15","modified_gmt":"2025-08-05T15:55:15","slug":"inquietud-en-partido-comunista-por-modificaciones-del-programa-de-jeannette-jara","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/08\/05\/inquietud-en-partido-comunista-por-modificaciones-del-programa-de-jeannette-jara\/","title":{"rendered":"Inquietud en Partido Comunista por modificaciones del programa de Jeannette Jara."},"content":{"rendered":"<p>El proceso de construcci\u00f3n del programa de gobierno de Jeannette Jara ha generado inquietud en militantes del Partido Comunista, ya que la candidata ha ido modificando algunas propuestas. Mientras el PC espera conocer las prioridades de Jara, esta ha relativizado la importancia del &#8220;sueldo vital&#8221; de $750 mil, descartado por su equipo econ\u00f3mico. <\/p>\n<p>Inquietud. Esa es la palabra que define la sensaci\u00f3n de algunos militantes del Partido Comunista frente a la construcci\u00f3n del nuevo programa de gobierno de Jeannette Jara. Y es que el &#8220;reseteo&#8221; que prometi\u00f3 la abanderada hace un par de semanas se est\u00e1 concretando, y con ello, Jara se ha ido alejando de algunas propuestas de su programa original.<\/p>\n<p>En ese sentido, el principal rostro del equipo econ\u00f3mico de su comando, Luis Escobar, desech\u00f3 una de las promesas emblem\u00e1ticas de la candidata: el &#8220;sueldo vital&#8221; de $750 mil. En entrevista con La Tercera, el economista plante\u00f3 que \u201cel consenso dentro del equipo es que llegar a $750 mil en cuatro a\u00f1os es bien dif\u00edcil. No puede ser un compromiso, porque hay cosas que uno no controla\u201d.<\/p>\n<p>Pese a ello, en el Partido Comunista optaron por la cautela. De hecho, el timonel del PC, Lautaro Carmona, sostuvo que se van a pronunciar una vez que la candidata \u201cd\u00e9 a conocer cu\u00e1les son las prioridades\u201d. <\/p>\n<p>Este lunes, tras participar en el conversatorio &#8220;Cumbre de las Regiones&#8221;, la candidata Jeannette Jara abord\u00f3 las declaraciones de Luis Escobar, relativizando su propuesta y planteando que -m\u00e1s all\u00e1 del monto- lo importante es avanzar en un sueldo que \u201calcance para vivir\u201d. En la instancia, la abanderada tambi\u00e9n matiz\u00f3 otra declaraci\u00f3n de Escobar, quien afirm\u00f3 que la exministra se identifica como socialdem\u00f3crata. Jara asegur\u00f3 que \u201ca m\u00ed nunca me ha gustado encasillarme ni en uno ni en otro lado\u201d.<\/p>\n<p>Adem\u00e1s, agreg\u00f3 que \u201ces evidente que la sociedad avanza en procesos. Yo creo que construyo como parte de la socialdemocracia. Me gustar\u00eda que hubiese un horizonte de cambio m\u00e1s profundo, pero en esta realidad es lo que hoy d\u00eda hay\u201d. <\/p>\n<p>Pero, volviendo a su programa econ\u00f3mico, la postura de Escobar fue valorada entre los partidos del Socialismo Democr\u00e1tico, donde han insistido en que la exministra debe \u201cmoderar\u201d sus medidas econ\u00f3micas. El secretario general del PPD, Jos\u00e9 Toro, que adem\u00e1s integra el comando de Jara, reconoci\u00f3 la necesidad de una propuesta m\u00e1s realista y ajustada a las circunstancias actuales.<\/p>\n<p>La conformaci\u00f3n de una lista \u00fanica para las elecciones parlamentarias a\u00fan no est\u00e1 asegurada. Este proceso ha generado roces entre los partidos m\u00e1s peque\u00f1os y los m\u00e1s grandes, cuestion\u00e1ndose el criterio \u201cel que tiene, mantiene\u201d. <\/p>\n<p>El diputado Jaime Mulet (FRVS), defensor de la opci\u00f3n de dos listas, plante\u00f3 que esta negociaci\u00f3n requiere \u201cinteligencia y buena fe\u201d y advirti\u00f3 que \u201ca veces eso no impera en pol\u00edtica\u201d.<\/p>\n<p>Acci\u00f3n Humanista, el Partido Liberal e incluso la Democracia Cristiana son algunos de los partidos que han marcado reparos frente a c\u00f3mo se ha llevado adelante la negociaci\u00f3n. El timonel del Partido Radical, Leonardo Cubillos, plante\u00f3 que el proceso de negociaci\u00f3n a\u00fan est\u00e1 abierta y cuestion\u00f3 el criterio de que ning\u00fan partido arriesgue su legalidad en la elecci\u00f3n de noviembre.<\/p>\n<p>La negociaci\u00f3n parlamentaria tambi\u00e9n ha generado \u201ccoletazos\u201d en la interna de algunos partidos, donde se han visto obligados a bajar a algunos de sus candidatos en pro de la unidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proceso de construcci\u00f3n del programa de gobierno de Jeannette Jara ha generado inquietud en militantes del Partido Comunista, ya que la candidata ha ido modificando algunas propuestas. Mientras el PC espera conocer las prioridades de Jara, esta ha relativizado la importancia del &#8220;sueldo vital&#8221; de $750 mil, descartado por su equipo econ\u00f3mico. Inquietud. Esa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18514,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-18515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/08\/homepiaiextractoscrapimg_webpprogramaJeannetteJaraPartidoComunistacandidata_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=18515"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18515\/revisions"}],"predecessor-version":[{"id":18516,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18515\/revisions\/18516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/18514"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=18515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=18515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=18515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}