{"id":18323,"date":"2025-07-30T17:19:20","date_gmt":"2025-07-30T20:19:20","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=18323"},"modified":"2025-07-30T17:19:20","modified_gmt":"2025-07-30T20:19:20","slug":"palestina-proyecta-crear-un-centro-de-entrenamiento-en-chile","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/07\/30\/palestina-proyecta-crear-un-centro-de-entrenamiento-en-chile\/","title":{"rendered":"Palestina proyecta crear un centro de entrenamiento en Chile"},"content":{"rendered":"<p>La selecci\u00f3n de f\u00fatbol de Palestina planea crear un centro de entrenamiento en Chile, seg\u00fan revel\u00f3 Ehab Abu Jazar, director t\u00e9cnico palestino. Este proyecto se desarrolla durante una visita que busca refugio para el crecimiento del equipo en tierras chilenas.<\/p>\n<p>Abu Jazar, nacido en Gaza y familiar con las dificultades causadas por el conflicto, viaj\u00f3 a Chile en busca de posibles seleccionados. Considera que este pa\u00eds alberga la mayor comunidad palestina fuera de los estados \u00e1rabes, lo que lo convierte en un lugar ideal para extender su proyecto.<\/p>\n<p>Su objetivo es establecer una escuela formativa y descubrir talentos j\u00f3venes. El centro de entrenamiento permitir\u00e1 a la selecci\u00f3n incorporar nuevos valores e incorporarlos al combinado nacional. Abu Jazar expres\u00f3: &#8220;Hemos recibido una cooperaci\u00f3n importante del Palestino con todos los recursos que tienen, por eso agradecemos al club&#8221;.<\/p>\n<p>El director t\u00e9cnico destac\u00f3 las dificultades enfrentadas en Palestina debido a la guerra contra Israel, donde al menos 700 deportistas han muerto. Abu Jazar afirm\u00f3: &#8220;Pr\u00e1cticamente no existe el deporte ahora en Palestina; no es solo que no haya torneos, sino que no hay actividades deportivas&#8221;. El torneo palestino se ha detenido desde octubre de 2023.<\/p>\n<p>El entrenador subray\u00f3 la importancia del proyecto para levantar la resiliencia y mantener el nombre de Palestina en competiciones internacionales. &#8220;Buscamos que el nombre y la bandera de Palestina est\u00e9n presentes, y seguir mejorando&#8221;, concluy\u00f3 Abu Jazar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La selecci\u00f3n de f\u00fatbol de Palestina planea crear un centro de entrenamiento en Chile, seg\u00fan revel\u00f3 Ehab Abu Jazar, director t\u00e9cnico palestino. Este proyecto se desarrolla durante una visita que busca refugio para el crecimiento del equipo en tierras chilenas. Abu Jazar, nacido en Gaza y familiar con las dificultades causadas por el conflicto, viaj\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18322,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-18323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/07\/homepiaiextractoscrapimg_predeterminadalaserenaradio_deportes-14.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=18323"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18323\/revisions"}],"predecessor-version":[{"id":18324,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18323\/revisions\/18324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/18322"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=18323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=18323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=18323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}