{"id":18305,"date":"2025-07-30T13:48:37","date_gmt":"2025-07-30T16:48:37","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=18305"},"modified":"2025-07-30T13:48:37","modified_gmt":"2025-07-30T16:48:37","slug":"matthei-se-reune-con-kast-tras-acusarlo-de-difundir-noticias-falsas","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/07\/30\/matthei-se-reune-con-kast-tras-acusarlo-de-difundir-noticias-falsas\/","title":{"rendered":"Matthei se re\u00fane con Kast tras acusarlo de difundir noticias falsas."},"content":{"rendered":"<p>Sin cruzar palabras y solo con un apret\u00f3n de manos. Esa fue la forma en que los candidatos presidenciales Evelyn Matthei (UDI, RN y Ev\u00f3poli) y Jose Antonio Kast (Partido Republicano) se saludaron en una actividad donde coincidieron en el Hogar de Cristo, dos d\u00edas despu\u00e9s de que Matthei anunciara acciones legales en contra de Republicanos por difundir noticias falsas en su contra en redes sociales.<\/p>\n<p>Kast estaba junto al precandidato Harold Mayne Nicholls en el acceso del sal\u00f3n de la actividad cuando lleg\u00f3 Matthei, quien salud\u00f3 de mano al republicano y con un beso a Mayne Nicholls, con quien luego convers\u00f3 por breves minutos antes de entrar a la actividad. Matthei fue consultada si era un buen momento para limar asperezas, pero no hubo respuesta.<\/p>\n<p>M\u00e1s temprano esta ma\u00f1ana, en Radio Pauta, la abanderada de Chile Vamos insisti\u00f3 en su postura de confrontar a Kast por difundir noticias falsas, al se\u00f1alar que \u201cel candidato Kast sigue esas cuentas, las retuitea, no hay duda alguna\u201d. Consultada si la hegemon\u00eda en la derecha est\u00e1 en juego en esta campa\u00f1a entre Chile Vamos y Republicanos, plante\u00f3 que &#8220;lo peor que podemos hacer, es hacer lo mismo que la Concertaci\u00f3n, que baj\u00f3 el mo\u00f1o y se dej\u00f3 arrasar&#8221;.<\/p>\n<p>En la actividad del Hogar de Cristo tambi\u00e9n asisten la candidata de los partidos del oficialismo, Jeannette Jara, y la carta del Partido Nacional Libertario, Johannes Kaiser.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sin cruzar palabras y solo con un apret\u00f3n de manos. Esa fue la forma en que los candidatos presidenciales Evelyn Matthei (UDI, RN y Ev\u00f3poli) y Jose Antonio Kast (Partido Republicano) se saludaron en una actividad donde coincidieron en el Hogar de Cristo, dos d\u00edas despu\u00e9s de que Matthei anunciara acciones legales en contra de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18304,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-18305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/07\/homepiaiextractoscrapimg_webpactividadMattheiKastdifundir_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=18305"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18305\/revisions"}],"predecessor-version":[{"id":18306,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18305\/revisions\/18306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/18304"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=18305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=18305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=18305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}