{"id":18251,"date":"2025-07-29T11:36:21","date_gmt":"2025-07-29T14:36:21","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=18251"},"modified":"2025-07-29T11:36:21","modified_gmt":"2025-07-29T14:36:21","slug":"la-senadora-carmen-gloria-aravena-denuncia-un-acoso-autoritario-por-parte-de-jose-antonio-kast","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/07\/29\/la-senadora-carmen-gloria-aravena-denuncia-un-acoso-autoritario-por-parte-de-jose-antonio-kast\/","title":{"rendered":"La senadora Carmen Gloria Aravena denuncia un acoso autoritario por parte de Jos\u00e9 Antonio Kast."},"content":{"rendered":"<p>La senadora Carmen Gloria Aravena, ex Partido Republicano, denunci\u00f3 un trato autoritario dentro del partido, aseverando haber sufrido acoso similar al ahora denunciado por Evelyn Matthei. En di\u00e1logo con CNN Chile, la legisladora relat\u00f3 que sufri\u00f3 ataques posteriores a su renuncia, justificada entonces por presiones del partido para rechazar la Comisi\u00f3n para la Paz y el Entendimiento.<\/p>\n<p>Despu\u00e9s de mi renuncia al Partido Republicano, que fue solicitada por el propio Jos\u00e9 Antonio Kast, yo viv\u00ed situaciones muy dolorosas de presiones a trav\u00e9s de redes de muchas de las cuentas que yo vi ah\u00ed (atacando a Matthei). Las reconozco porque hablaron pestes de m\u00ed.<\/p>\n<p>Asimismo, dijo que debi\u00f3 \u201cdenunciar m\u00faltiples cuentas por acoso, discursos de odio y mentiras\u201d, advirtiendo que prefiri\u00f3 no responder a cuentas por el \u201cmiedo\u201d que le generaba la situaci\u00f3n. Enfatiz\u00f3 que quienes siguen al Partido Republicano tienen un tema con las burlas, y ha habido mucha m\u00e1s mala suerte para las mujeres cuando han tenido una disidencia o diferencia de opini\u00f3n.<\/p>\n<p>Aravena subray\u00f3 en su cr\u00edtica hacia el partido, indicando que \u201ces triste la experiencia. No hay valoraci\u00f3n por tu trabajo legislativo, (\u2026) la valoraci\u00f3n es cu\u00e1nto apoyas a este grupo de personas que es el partido\u201d. <\/p>\n<p>El Partido Republicano, con sus muchas virtudes, es para Aravena absolutamente autoritario en su forma de hacer pol\u00edtica. En el l\u00edmite del respeto a la humanidad, al ser humano, a la dignidad y sobre todo a las mujeres, la legisladora ve una falta de valor.<\/p>\n<p>Psicol\u00f3gicamente y psiqui\u00e1tricamente es muy dif\u00edcil vivir el acoso de Republicanos en redes sociales, advirti\u00f3 Aravena. En su momento, el timonel del partido, Arturo Squella, le dijo \u201ccosas terribles\u201d.<\/p>\n<p>Finalmente, sobre la posibilidad de votar por Jos\u00e9 Antonio Kast, la senadora expres\u00f3 que \u201chay muy poca gente experta y especialista detr\u00e1s de Jos\u00e9 Antonio Kast. Usted ve lo que ve, porque no hay m\u00e1s. (\u2026) El resto fuimos todos ej\u00e9rcito\u201d. Republicanos, agreg\u00f3, no es una buena alternativa de Gobierno.<\/p>\n<p>Concluyendo, Aravena dijo: \u201cser\u00eda muy dif\u00edcil votar por \u00e9l. No tiene la experiencia p\u00fablica ni privada para dirigir Chile.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La senadora Carmen Gloria Aravena, ex Partido Republicano, denunci\u00f3 un trato autoritario dentro del partido, aseverando haber sufrido acoso similar al ahora denunciado por Evelyn Matthei. En di\u00e1logo con CNN Chile, la legisladora relat\u00f3 que sufri\u00f3 ataques posteriores a su renuncia, justificada entonces por presiones del partido para rechazar la Comisi\u00f3n para la Paz y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18250,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[83],"tags":[],"class_list":["post-18251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/07\/homepiaiextractoscrapimg_webppartidoacosoAntonioKastmuy_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=18251"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18251\/revisions"}],"predecessor-version":[{"id":18252,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18251\/revisions\/18252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/18250"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=18251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=18251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=18251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}