{"id":18063,"date":"2025-07-24T19:28:13","date_gmt":"2025-07-24T22:28:13","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=18063"},"modified":"2025-07-24T19:28:13","modified_gmt":"2025-07-24T22:28:13","slug":"chicharito-pide-disculpas-por-sus-declaraciones-machistas","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/07\/24\/chicharito-pide-disculpas-por-sus-declaraciones-machistas\/","title":{"rendered":"Chicharito pide disculpas por sus declaraciones machistas"},"content":{"rendered":"<p>Javier &#8220;Chicharito&#8221; Hern\u00e1ndez, ex delantero del Real Madrid, us\u00f3 Instagram para pedir disculpas por comentarios machistas. &#8220;Agradezco de coraz\u00f3n a todos los que me han apoyado y a quienes me exigen ser una mejor persona. Lamento profundamente cualquier confusi\u00f3n o malestar que mis palabras recientes causaron: nunca fue mi intenci\u00f3n limitar, herir ni dividir&#8221;, expres\u00f3 el jugador del Guadalajara.<\/p>\n<p>El m\u00e1ximo goleador de la selecci\u00f3n mexicana ha usado en reiteradas ocasiones su cuenta de TikTok para subir videos en los que promueve estereotipos de g\u00e9nero. En uno de sus mensajes asegur\u00f3: &#8220;las mujeres \u2018acaban con la masculinidad\u2019 al no dedicarse a labores del hogar&#8221;.<\/p>\n<p>Sus declaraciones fueron condenadas por diversos actores, incluyendo la presidenta de M\u00e9xico, Claudia Sheinbaum; el Guadalajara; PUMA (marca que patrocina a Chicharito Hern\u00e1ndez); y la Federaci\u00f3n Mexicana de F\u00fatbol. Esta \u00faltima mult\u00f3 al ex artillero del Manchester United.<\/p>\n<p>&#8220;Como padre, hombre y miembro de esta comunidad, mi prioridad es actuar con respeto, humildad y responsabilidad. Estoy escuchando, reflexionando y comprometido a expresarme con una mejor claridad y sensibilidad, especialmente en temas tan delicados&#8221;, a\u00f1adi\u00f3 Hern\u00e1ndez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Javier &#8220;Chicharito&#8221; Hern\u00e1ndez, ex delantero del Real Madrid, us\u00f3 Instagram para pedir disculpas por comentarios machistas. &#8220;Agradezco de coraz\u00f3n a todos los que me han apoyado y a quienes me exigen ser una mejor persona. Lamento profundamente cualquier confusi\u00f3n o malestar que mis palabras recientes causaron: nunca fue mi intenci\u00f3n limitar, herir ni dividir&#8221;, expres\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18062,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-18063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/07\/homepiaiextractoscrapimg_webpChicharitoChicharito_0.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=18063"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18063\/revisions"}],"predecessor-version":[{"id":18064,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/18063\/revisions\/18064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/18062"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=18063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=18063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=18063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}