{"id":17174,"date":"2025-07-01T09:52:31","date_gmt":"2025-07-01T12:52:31","guid":{"rendered":"https:\/\/laserenaradio.cl\/web\/?p=17174"},"modified":"2025-07-01T09:52:31","modified_gmt":"2025-07-01T12:52:31","slug":"santiago-wanderers-elimina-a-deportes-antofagasta","status":"publish","type":"post","link":"https:\/\/laserenaradio.cl\/web\/2025\/07\/01\/santiago-wanderers-elimina-a-deportes-antofagasta\/","title":{"rendered":"Santiago Wanderers elimina a Deportes Antofagasta."},"content":{"rendered":"<p>Deportes Antofagasta perdi\u00f3 2-3 con Santiago Wanderers en el estadio Calvo y Bascu\u00f1\u00e1n, sellando su paso a cuartos de final de la Copa Chile. El elenco &#8216;caturro&#8217; hab\u00eda vencido 3-0 en el encuentro de ida, por lo que ten\u00eda bien encaminada su clasificaci\u00f3n a la ronda de ocho mejores del tradicional torneo.<\/p>\n<p>Se ilusion\u00f3 Antofagasta con la remontada este lunes, luego de ponerse en ventaja gracias a un autogol de Sergio Felipe a los 9 minutos. Pero Wanderers no quiso zozobras y, en el 39&#8242;, Joaqu\u00edn Pereyra marc\u00f3 el 1-1 con un potente remate de derecha.<\/p>\n<p>Ya en el complemento, Antofagasta volvi\u00f3 a estar arriba con el marcador luego del penal convertido por Tob\u00edas Figueroa a los 51&#8242;. La ilusi\u00f3n de los nortinos se acab\u00f3 a los 76&#8242;, cuando Maximiliano Cuadra puso el 2-2 con un tiro desde afuera del \u00e1rea. Y a los 88&#8242;, Cuadra Repiti\u00f3 -esta vez tras asistencia de Axel Herrera- para sellar el 2-3 final a favor de Santiago Wanderers.<\/p>\n<p>Por cuartos de final de Copa Chile, los porte\u00f1os se enfrentar\u00e1n a Deportes La Serena o San Luis de Quillota (la ida fue 3-1 a favor de los &#8216;Canarios&#8217;).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deportes Antofagasta perdi\u00f3 2-3 con Santiago Wanderers en el estadio Calvo y Bascu\u00f1\u00e1n, sellando su paso a cuartos de final de la Copa Chile. El elenco &#8216;caturro&#8217; hab\u00eda vencido 3-0 en el encuentro de ida, por lo que ten\u00eda bien encaminada su clasificaci\u00f3n a la ronda de ocho mejores del tradicional torneo. Se ilusion\u00f3 Antofagasta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17173,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_paywall_metabox":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[84],"tags":[],"class_list":["post-17174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"jetpack_featured_media_url":"https:\/\/laserenaradio.cl\/web\/wp-content\/uploads\/2025\/07\/homepiaiextractoscrapimg_predeterminadalaserenaradio_deportes-1.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/17174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/comments?post=17174"}],"version-history":[{"count":1,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/17174\/revisions"}],"predecessor-version":[{"id":17175,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/posts\/17174\/revisions\/17175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media\/17173"}],"wp:attachment":[{"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/media?parent=17174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/categories?post=17174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laserenaradio.cl\/web\/wp-json\/wp\/v2\/tags?post=17174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}